{"id":2604,"date":"2022-12-22T02:14:20","date_gmt":"2022-12-21T23:14:20","guid":{"rendered":"https:\/\/fezzanu.edu.ly\/fecon\/?p=2604"},"modified":"2022-12-22T02:24:36","modified_gmt":"2022-12-21T23:24:36","slug":"accounting-administration","status":"publish","type":"post","link":"https:\/\/fezzanu.edu.ly\/fecon\/accounting-administration\/","title":{"rendered":"\u0627\u0644\u0645\u062d\u0627\u0633\u0628\u0629 \u0627\u0644\u0627\u062f\u0627\u0631\u064a\u0629"},"content":{"rendered":"<p>[vc_row][vc_column]\t\t\r\n\r\n\t\r\n<div class=\"section-full content-inner\">\t\r\n\t<div class=\"container\">\t\r\n\t\t<div class=\"row equal-col\">\r\n\t\t\t\t\t<div class=\"col-lg-12\">\r\n\t\t\t\t<div class=\"row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-12 m-b30\">\r\n\t\t\t\t\t\t\t<h2 class=\"m-b10 m-t0\">\r\n\t\t\t\t\t\t\t\t\u0625\u062f\u0627\u0631\u0629 \u0627\u0644\u0645\u062d\u0627\u0641\u0638 \u0627\u0644\u0627\u0633\u062a\u062b\u0645\u0627\u0631\u064a\u0629\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<div class=\"dez-accordion space\" id=\"accordionF48C224\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22190\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0646\u0638\u0631\u0629\u0639\u0627\u0645\u0629\u0639\u0646 \u0627\u0644\u0645\u0642\u0631\u0631 Overview\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22190\" class=\"acod-body collapse show\" data-parent=\"#accordionF48C224\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0627\u0644\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0645\u0641\u0647\u0648\u0645 \u0627\u0644\u0627\u0633\u062a\u062b\u0645\u0627\u0631 \u0648\u0627\u0644\u0645\u062d\u0627\u0641\u0638 \u0627\u0644\u0627\u0633\u062a\u062b\u0645\u0627\u0631\u064a\u0629 \u0648\u0623\u0646\u0648\u0627\u0639\u0647\u0627 \u0648\u0633\u064a\u0627\u0633\u0629 \u0627\u0644\u0627\u0633\u062a\u062b\u0645\u0627\u0631 \u0641\u064a\u0647\u0627 \u060c \u0648\u0637\u0631\u0642 \u0642\u064a\u0627\u0633 \u0627\u0644\u0639\u0648\u0627\u0626\u062f \u0648\u062a\u0642\u064a\u064a\u0645\u0647\u0627 \u060c \u0648\u0623\u0645\u062b\u0644\u0629 \u0639\u0645\u0644\u064a\u0629 \u062d\u0648\u0644 \u0625\u062f\u0627\u0631\u0629 \u0627\u0644\u0645\u062d\u0627\u0641\u0638 \u0648\u0643\u064a\u0641\u064a\u0629 \u0627\u0644\u062d\u062f \u0645\u0646 \u0627\u0644\u0645\u062e\u0627\u0637\u0631 \u0627\u0644\u062a\u064a \u062a\u0624\u062b\u0631 \u0641\u064a \u0627\u0644\u0639\u0648\u0627\u0626\u062f \u0648\u0635\u0646\u0627\u062f\u064a\u0642 \u0627\u0644\u0627\u0633\u062a\u062b\u0645\u0627\u0631\u00a0\u00a0\u0648\u0645\u062e\u0627\u0637\u0631\u0647\u0627.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22290\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u0645\u062e\u0631\u062c\u0627\u062a\u0627\u0644\u062a\u0639\u0644\u064a\u0645\u064a\u0629 (ILOs)\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22290\" class=\"acod-body collapse \" data-parent=\"#accordionF48C224\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0627\u0644\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0645\u0641\u0647\u0648\u0645 \u0627\u0644\u0627\u0633\u062a\u062b\u0645\u0627\u0631 \u0648\u0627\u0644\u0645\u062d\u0627\u0641\u0638 \u0627\u0644\u0627\u0633\u062a\u062b\u0645\u0627\u0631\u064a\u0629 \u0648\u0623\u0646\u0648\u0627\u0639\u0647\u0627 \u0648\u0633\u064a\u0627\u0633\u0627\u062a \u0625\u062f\u0627\u0631\u062a\u0647\u0627 , , \u0648\u0637\u0631\u0642 \u0642\u064a\u0627\u0633 \u0627\u0644\u0639\u0648\u0627\u0626\u062f\u00a0 \u0648\u062a\u0642\u064a\u064a\u0645\u0647\u0627 , \u0648\u0623\u0645\u062b\u0644\u0629 \u0639\u0645\u0644\u064a\u0629 \u062d\u0648\u0644 \u0625\u062f\u0627\u0631\u0629 \u0627\u0644\u0645\u062d\u0627\u0641\u0638 \u0643\u0627\u0641\u0629\u00a0 , \u0648\u0643\u064a\u0641\u064a\u0629 \u0627\u0644\u062d\u062f \u0645\u0646 \u0627\u0644\u0645\u062e\u0627\u0637\u0631 \u0627\u0644\u062a\u064a \u062a\u0624\u062b\u0631 \u0641\u064a \u0627\u0644\u0639\u0648\u0627\u0626\u062f \u0648 \u0648\u0645\u0642\u0627\u064a\u064a\u0633 \u0648\u0646\u0645\u0627\u0630\u062c \u062a\u0642\u064a\u064a\u0645 \u0623\u062f\u0627\u0621 \u0645\u062f\u0631\u0627\u0621 \u0627\u0644\u0645\u062d\u0627\u0641\u0638 , \u0648\u0627\u0644\u0645\u0634\u062a\u0642\u0627\u062a \u0627\u0644\u0645\u0627\u0644\u064a\u0629 \u0648\u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22390\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0637\u0631\u064a\u0642\u0629\u0627\u0644\u062a\u062f\u0631\u064a\u0633 Teaching Strategy\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22390\" class=\"acod-body collapse \" data-parent=\"#accordionF48C224\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>1 . \u0627\u0644\u0645\u062d\u0627\u0636\u0631\u0627\u062a \u0627\u0644\u062f\u0631\u0627\u0633\u064a\u0629 .<\/p>\n<p>2 .\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 .<\/p>\n<p>3 .\u0627\u0639\u062f\u0627\u062f \u0627\u0648\u0631\u0627\u0642 \u0628\u062d\u062b\u064a\u0629 \u0648\u0645\u0646\u0627\u0642\u0634\u062a\u0647\u0627 .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22490\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u062a\u0642\u064a\u064a\u0645 Assessment\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22490\" class=\"acod-body collapse \" data-parent=\"#accordionF48C224\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u062a\u062a\u0645 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0639\u0645\u0644 \u0627\u0645\u062a\u062d\u0627\u0646 \u062a\u062d\u0631\u064a\u0631\u064a \u0646\u0635\u0641\u0649\u060c \u0648\u0634\u0641\u0648\u064a\u060c \u0648\u0648\u0627\u062c\u0628 \u062f\u0631\u0627\u0633\u064a\u060c \u0648\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 \u0648\u0627\u0645\u062a\u062d\u0627\u0646 \u0646\u0647\u0627\u0626\u0649. .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-12 m-b30\">\r\n\t\t\t\t\t\t\t<h2 class=\"m-b10 m-t0\">\r\n\t\t\t\t\t\t\t\t\u0627\u0644\u0623\u0642\u062a\u0635\u0627\u062f\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<p>\r\n\t\t\t\t\t\t\t\t\u062a\u0648\u0635\u064a\u0641 \u0627\u0644\u0645\u0642\u0631\u0631\u0627\u062a \u0644\u0642\u0633\u0645 \u0627\u0644\u0625\u0642\u062a\u0635\u0627\u062f\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<div class=\"dez-accordion space\" id=\"accordionF48C2217\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22167\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0646\u0638\u0631\u0629 \u0639\u0627\u0645\u0629 \u0639\u0646 \u0627\u0644\u0645\u0642\u0631\u0631\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22167\" class=\"acod-body collapse show\" data-parent=\"#accordionF48C2217\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0627\u0633\u0645 \u0627\u0644\u0645\u0642\u0631\u0631: \u0645\u062d\u0627\u0633\u0628\u0629 \u0627\u0644\u062a\u0643\u0627\u0644\u064a\u0641<br \/>\n\u0631\u0645\u0632 \u0627\u0644\u0645\u0642\u0631\u0631:  211<br \/>\n \u064a\u062a\u0646\u0627\u0648\u0644 \u0627\u0644\u0645\u0642\u0631\u0651\u0631 \u0645\u0641\u0647\u0648\u0645 \u0627\u0644\u062a\u0643\u0644\u0641\u0629 \u0648\u0623\u0647\u062f\u0627\u0641 \u0645\u062d\u0627\u0633\u0628\u0629 \u0627\u0644\u062a\u0643\u0627\u0644\u064a\u0641  \u062a\u062d\u062f\u064a\u062f \u0639\u0646\u0627\u0635\u0631 \u0627\u0644\u062a\u0643\u0644\u0641\u0629 \u0648\u0623\u0633\u0627\u0644\u064a\u0628 \u062a\u0628\u0648\u064a\u0628\u0647\u0627\u061b \u0623\u0646\u0638\u0645\u0629 \u0645\u062d\u0627\u0633\u0628\u0629 \u0627\u0644\u062a\u0643\u0627\u0644\u064a\u0641 \u0648\u0627\u0644\u0646\u0638\u0631\u064a\u0651\u0627\u062a \u0627\u0644\u0645\u062a\u0639\u0644\u0651\u0642\u0629 \u0628\u0647\u0627\u061b \u0642\u064a\u0627\u0633 \u062a\u0643\u0644\u0641\u0629 \u0627\u0644\u0645\u0648\u0627\u062f \u0627\u0644\u0645\u0628\u0627\u0634\u0631\u0629\u061b \u0637\u0631\u0627\u0626\u0642 \u062a\u0633\u0639\u064a\u0631 \u0627\u0644\u062e\u0627\u0645\u0627\u062a \u0648\u0627\u0644\u0645\u0648\u0627\u062f \u0627\u0644\u0623\u0648\u0644\u064a\u0651\u0629 \u0648\u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0645\u062e\u0632\u0648\u0646 \u0627\u0644\u0633\u0644\u0639\u064a\u061b \u0642\u064a\u0627\u0633 \u062a\u0643\u0644\u0641\u0629 \u0627\u0644\u0639\u0645\u0644 \u0627\u0644\u0628\u0634\u0631\u064a\u061b \u0642\u064a\u0627\u0633 \u0627\u0644\u062a\u0643\u0627\u0644\u064a\u0641 \u063a\u064a\u0631 \u0627\u0644\u0645\u0628\u0627\u0634\u0631\u0629.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22267\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u0645\u062e\u0631\u062c\u0627\u062a \u0627\u0644\u062a\u0639\u0644\u064a\u0645\u064a\u0629\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22267\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2217\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0639\u0646\u062f \u0646\u0647\u0627\u064a\u0629 \u0627\u0644\u0645\u0642\u0631\u0631 \u064a\u0643\u0648\u0646 \u0627\u0644\u0637\u0627\u0644\u0628 \u0642\u0627\u062f\u0631\u0627 \u0639\u0644\u0649:<br \/>\n&#8211; \u062a\u062d\u062f\u064a\u062f \u0639\u0646\u0627\u0635\u0631 \u0627\u0644\u062a\u0643\u0644\u0641\u0629 \u0648\u0645\u0639\u0631\u0641\u0629 \u0623\u0633\u0627\u0644\u064a\u0628 \u062a\u0628\u0648\u064a\u0628\u0647\u0627<br \/>\n&#8211; \u0645\u0639\u0631\u0641\u0629 \u0637\u0631\u0627\u0626\u0642 \u062a\u0633\u0639\u064a\u0631 \u0627\u0644\u0645\u0648\u0627\u062f \u0627\u0644\u0623\u0648\u0644\u064a\u0651\u0629 \u0648\u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0645\u062e\u0632\u0648\u0646 \u0627\u0644\u0633\u0644\u0639\u064a \u0648\u062a\u0637\u0628\u064a\u0642\u0647\u0627.<br \/>\n&#8211; \u0645\u0639\u0631\u0641\u0629 \u0623\u0633\u0627\u0644\u064a\u0628 \u0642\u064a\u0627\u0633 \u062a\u0643\u0644\u0641\u0629 \u0627\u0644\u0639\u0645\u0644 \u0627\u0644\u0628\u0634\u0631\u064a \u0648\u062a\u0637\u0628\u064a\u0642\u0647\u0627.<br \/>\n&#8211; \u0642\u064a\u0627\u0633 \u0627\u0644\u062a\u0643\u0627\u0644\u064a\u0641 \u063a\u064a\u0631 \u0627\u0644\u0645\u0628\u0627\u0634\u0631\u0629 \u0648\u062a\u0637\u0628\u064a\u0642\u0647\u0627 .<br \/>\n&#8211; \u0637\u0631\u0642 \u062a\u062d\u062f\u064a\u062f \u062a\u0643\u0644\u0641\u0629 \u0627\u0644\u0645\u0646\u062a\u062c .<br \/>\n&#8211; \u0645\u0639\u0631\u0642\u0629 \u0623\u0646\u0638\u0645\u0629 \u0627\u0644\u062a\u0643\u0627\u0644\u064a\u0641 .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22367\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u062f\u0631\u064a\u0633\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22367\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2217\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0633\u064a\u0642\u062f\u0645 \u0627\u0644\u0645\u0642\u0631\u0631 \u0644\u0644\u0637\u0627\u0644\u0628 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0645\u062d\u0627\u0636\u0631\u0627\u062a\u060c \u0648\u062d\u0644\u0642\u0627\u062a \u0627\u0644\u0646\u0642\u0627\u0634\u060c \u0648\u0627\u0644\u0623\u0646\u0634\u0637\u0629 \u0627\u0644\u0639\u0645\u0644\u064a\u0629<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22467\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u062a\u0642\u064a\u064a\u0645\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22467\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2217\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 (\u0627\u0645\u062a\u062d\u0627\u0646 \u0646\u0635\u0641\u064a \u060c \u0646\u0647\u0627\u0626\u064a \u060c \u0648\u0631\u0642\u0627\u062a \u0639\u0645\u0644 \u060c \u0645\u0634\u0627\u0631\u0643\u0627\u062a ) \u0639\u0644\u0649 \u0623\u0646 \u062a\u0643\u0648\u0646 \u0627\u0644\u062f\u0631\u062c\u0627\u062a \u0645\u0642\u0633\u0645\u0629 \u0639\u0644\u064a\u0647\u0646 \u0628\u062d\u0633\u0628 \u0645\u0627 \u064a\u0631\u0627\u0647 \u0627\u0644\u0623\u0633\u062a\u0627\u0630 \u0645\u0646\u0627\u0633\u0628\u0627.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-12 m-b30\">\r\n\t\t\t\t\t\t\t<h2 class=\"m-b10 m-t0\">\r\n\t\t\t\t\t\t\t\t\u0627\u0644\u0625\u062f\u0627\u0631\u0629 \u0627\u0644\u0645\u0627\u0644\u064a\u0629\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<div class=\"dez-accordion space\" id=\"accordionF48C2219\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22180\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0646\u0638\u0631\u0629\u0639\u0627\u0645\u0629\u0639\u0646\u0627\u0644\u0645\u0642\u0631\u0631 Overview\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22180\" class=\"acod-body collapse show\" data-parent=\"#accordionF48C2219\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u064a\u062f\u0631\u0633 \u0627\u0644\u0637\u0644\u0627\u0628 \u0641\u064a \u0647\u062f\u0627 \u0627\u0644\u0645\u0642\u0631\u0631\u0645\u062f\u062e\u0644\u0625\u0644\u0649\u0627\u0644\u0625\u062f\u0627\u0631\u0629\u0627\u0644\u0645\u0627\u0644\u064a\u0629\u060c \u0628\u064a\u0626\u0629\u0627\u0644\u0625\u062f\u0627\u0631\u0629\u0627\u0644\u0645\u0627\u0644\u064a\u0629\u060c \u062a\u062d\u0644\u064a\u0644\u0627\u0644\u0642\u0648\u0627\u0626\u0645\u0627\u0644\u0645\u0627\u0644\u064a\u0629.\u060c \u0627\u0644\u0642\u064a\u0645\u0629\u0627\u0644\u0632\u0645\u0646\u064a\u0629\u0644\u0644\u0646\u0642\u0648\u062f\u060c \u0648 \u0627\u0644\u062a\u062d\u0644\u064a\u0644\u0627\u0644\u0645\u0627\u0644\u064a\u060c \u062a\u0642\u064a\u064a\u0645\u0627\u0644\u0623\u0648\u0631\u0627\u0642\u0627\u0644\u0645\u0627\u0644\u064a\u0629 .\u0627\u0644\u062a\u0645\u0648\u064a\u0644\u0642\u0635\u064a\u0631\u0648\u0637\u0648\u064a\u0644\u0627\u0644\u0623\u062c\u0644\u060c \u0625\u062f\u0627\u0631\u0629\u0631\u0623\u0633\u0627\u0644\u0645\u0627\u0644\u0627\u0644\u0639\u0627\u0645\u0644.\u0625\u062f\u0627\u0631\u0629\u0627\u0644\u0627\u0626\u062a\u0645\u0627\u0646 \u0648\u0627\u0644\u0645\u062e\u0632\u0648\u0646\u060c \u062a\u0642\u064a\u064a\u0645\u0627\u0644\u0627\u0633\u062a\u062b\u0645\u0627\u0631\u0627\u062a\u0627\u0644\u0645\u0627\u0644\u064a\u0629\u060c \u0627\u0644\u0641\u0634\u0644\u0627\u0644\u0645\u0627\u0644\u064a.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22280\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u0645\u062e\u0631\u062c\u0627\u062a \u0627\u0644\u062a\u0639\u0644\u064a\u0645\u064a\u0629 (ILOs)\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22280\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2219\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0639\u0646\u062f \u0627\u0644\u0627\u0646\u062a\u0647\u0627\u0621 \u0645\u0646 \u0647\u062f\u0627 \u0627\u0644\u0645\u0642\u0631\u0631 \u0633\u064a\u0643\u0648\u0646 \u0627\u0644\u0637\u0627\u0644\u0628 \u0642\u0627\u062f\u0631\u0627\u064b \u0639\u0644\u0649:<\/p>\n<p><strong>1<\/strong>. \u0645\u0639\u0631\u0641\u0629 \u0645\u0641\u0627\u0647\u064a\u0645 \u0648\u0645\u0639\u0627\u0631\u0641 \u062a\u0633\u0627\u0639\u062f\u0647\u0645 \u0639\u0644\u0649 \u0641\u0647\u0645 \u0627\u0644\u0645\u0634\u0643\u0644\u0627\u062a \u0627\u0644\u0645\u0627\u0644\u064a\u0629 \u0627\u0644\u062a\u064a \u062a\u0648\u0627\u062c\u0647 \u0645\u0646\u0638\u0645\u0627\u062a \u0627\u0644\u0627\u0639\u0645\u0627\u0644 \u0628\u0645\u062e\u062a\u0644\u0641 \u0627\u0634\u0643\u0627\u0644\u0647\u0627.<\/p>\n<p><strong>2<\/strong>.\u00a0 \u0627\u0643\u0633\u0627\u0628 \u0627\u0644\u0637\u0644\u0628\u0629 \u0627\u0644\u0645\u0647\u0627\u0631\u0627\u062a \u0627\u0644\u0636\u0631\u0648\u0631\u064a\u0629 \u0627\u0644\u062a\u064a \u062a\u0645\u0643\u0646\u0647\u0645 \u0645\u0646 \u062a\u062d\u0644\u064a\u0644 \u0627\u0644\u0645\u0631\u0643\u0632 \u0627\u0644\u0645\u0627\u0644\u064a \u0648\u062a\u062d\u062f\u064a\u062f \u0645\u0635\u0627\u062f\u0631 \u0627\u0644\u062a\u0645\u0648\u064a\u0644 \u0648\u062a\u0642\u064a\u064a\u0645 \u0627\u0644\u0627\u0633\u062a\u062b\u0645\u0627\u0631\u0627\u062a \u0648\u063a\u064a\u0631 \u0630\u0644\u0643.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22380\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0637\u0631\u064a\u0642\u0629\u0627\u0644\u062a\u062f\u0631\u064a\u0633 Teaching Strategy\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22380\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2219\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0633\u064a\u0642\u062f\u0645 \u0627\u0644\u0645\u0642\u0631\u0631 \u0644\u0644\u0637\u0627\u0644\u0628:<\/p>\n<ul>\n<li>\u0645\u062d\u0627\u0636\u0631\u0627\u062a \u0645\u0646\u0647\u062c\u064a\u0629 \u0646\u0638\u0631\u064a\u0629 \u0648\u0639\u0645\u0644\u064a\u0629.<\/li>\n<li>\u0639\u0631\u0648\u0636 \u062a\u0642\u062f\u064a\u0645\u064a\u0629 \u0645\u062a\u0639\u0644\u0642\u0629 \u0628\u0627\u0644\u0645\u0642\u0631\u0631<\/li>\n<li>\u0627\u0644\u0646\u0634\u0627\u0637 \u0648\u0627\u0644\u0645\u0634\u0627\u0631\u0643\u0629 \u0648\u0627\u0644\u0648\u0627\u062c\u0628\u0627\u062a<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22480\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u062a\u0642\u064a\u064a\u0645 Assessment\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22480\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2219\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 (\u0627\u0645\u062a\u062d\u0627\u0646 \u0646\u0635\u0641\u064a\u060c \u0646\u0647\u0627\u0626\u064a \u060c\u0648\u0631\u0642\u0627\u062a \u0639\u0645\u0644) \u0639\u0644\u0649 \u0623\u0646 \u062a\u0643\u0648\u0646 \u0627\u0644\u062f\u0631\u062c\u0627\u062a \u0645\u0642\u0633\u0645\u0629 \u0639\u0644\u064a\u0647\u0646 \u0628\u062d\u0633\u0628 \u0645\u0627 \u064a\u0631\u0627\u0647 \u0627\u0644\u0623\u0633\u062a\u0627\u0630 \u0645\u0646\u0627\u0633\u0628 .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-12 m-b30\">\r\n\t\t\t\t\t\t\t<h2 class=\"m-b10 m-t0\">\r\n\t\t\t\t\t\t\t\t\u0627\u0644\u0627\u062f\u0627\u0631\u0629 \u0627\u0644\u0627\u0643\u062a\u0631\u0648\u0646\u064a\u0629\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<div class=\"dez-accordion space\" id=\"accordionF48C2221\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22177\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0646\u0638\u0631\u0629\u0639\u0627\u0645\u0629\u0639\u0646\u0627\u0644\u0645\u0642\u0631\u0631 Overview\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22177\" class=\"acod-body collapse show\" data-parent=\"#accordionF48C2221\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u064a\u062f\u0631\u0633 \u0627\u0644\u0637\u0644\u0627\u0628 \u0641\u064a \u0647\u062f\u0627 \u0627\u0644\u0645\u0642\u0631\u0631 \u0645\u0641\u0647\u0648\u0645\u0627\u0644\u0627\u062f\u0627\u0631\u0629\u0627\u0644\u0627\u0643\u062a\u0631\u0648\u0646\u064a\u0629\u0648\u0623\u0628\u0639\u0627\u062f\u0647\u0627\u0648\u0639\u0644\u0627\u0642\u062a\u0647\u0627\u0628\u0627\u0644\u0645\u0641\u0627\u0647\u064a\u0645\u0627\u0644\u0625\u062f\u0627\u0631\u064a\u0629\u0627\u0644\u0623\u062e\u0631\u0649\u060c \u0623\u0647\u0645\u064a\u0629\u0648\u0623\u0647\u062f\u0627\u0641\u0627\u0644\u0625\u062f\u0627\u0631\u0629\u0627\u0644\u0627\u0643\u062a\u0631\u0648\u0646\u064a\u0629\u060c \u0645\u0628\u0627\u062f\u0626\u0627\u0644\u0627\u062f\u0627\u0631\u0629\u0627\u0644\u0627\u0643\u062a\u0631\u0648\u0646\u064a\u0629\u0648\u0645\u062a\u0637\u0644\u0628\u0627\u062a\u0646\u062c\u0627\u062d\u0627\u0633\u062a\u062e\u062f\u0627\u0645\u0647\u0627\u0641\u064a\u0627\u0644\u0645\u0646\u0638\u0645\u0627\u062a\u060c \u062e\u0637\u0648\u0627\u062a\u0627\u0644\u062a\u062d\u0648\u0644\u0646\u062d\u0648\u0627\u0644\u0627\u062f\u0627\u0631\u0629\u0627\u0644\u0627\u0643\u062a\u0631\u0648\u0646\u064a\u0629\u060c \u0623\u0646\u0645\u0627\u0637\u0627\u0644\u0627\u062f\u0627\u0631\u0629\u0627\u0644\u0627\u0643\u062a\u0631\u0648\u0646\u064a\u0629\u060c \u0645\u0639\u0648\u0642\u0627\u062a\u0627\u0644\u0627\u062f\u0627\u0631\u0629\u0627\u0644\u0627\u0643\u062a\u0631\u0648\u0646\u064a\u0629\u060c \u0645\u0645\u0627\u0631\u0633\u0629\u0627\u0644\u0627\u062f\u0627\u0631\u0629\u0627\u0644\u0627\u0643\u062a\u0631\u0648\u0646\u064a\u0629\u0644\u0648\u0638\u064a\u0641\u0629\u0627\u0644\u0627\u0646\u062a\u0627\u062c\u0648\u0627\u0644\u062a\u0633\u0648\u064a\u0642\u0648\u0627\u0644\u0645\u0648\u0627\u0631\u062f\u0627\u0644\u0628\u0634\u0631\u064a\u0629\u0648\u0627\u0644\u0645\u0627\u0644\u064a\u0629.\u0627\u0644\u062d\u0643\u0648\u0645\u0629\u0627\u0644\u0627\u0643\u062a\u0631\u0648\u0646\u064a\u0629.\u0627\u0644\u0645\u0646\u0638\u0645\u0629\u0627\u0644\u0631\u0642\u0645\u064a\u0629\u060c \u0627\u0644\u062a\u062c\u0627\u0631\u0629\u0627\u0644\u0627\u0643\u062a\u0631\u0648\u0646\u064a\u0629.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22277\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u0645\u062e\u0631\u062c\u0627\u062a \u0627\u0644\u062a\u0639\u0644\u064a\u0645\u064a\u0629Intended Learning Outcomes (ILOs)\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22277\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2221\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0639\u0646\u062f \u0627\u0644\u0627\u0646\u062a\u0647\u0627\u0621 \u0645\u0646 \u0647\u062f\u0627 \u0627\u0644\u0645\u0642\u0631\u0631 \u0633\u064a\u0643\u0648\u0646 \u0627\u0644\u0637\u0627\u0644\u0628 \u0642\u0627\u062f\u0631\u0627\u064b \u0639\u0644\u0649:<\/p>\n<ul>\n<li>\u0645\u0639\u0631\u0641\u0629\u0645\u0641\u0647\u0648\u0645\u0627\u0644\u0627\u062f\u0627\u0631\u0629\u0627\u0644\u0627\u0643\u062a\u0631\u0648\u0646\u064a\u0629\u0648\u0627\u0644\u0641\u0631\u0642\u0628\u064a\u0646\u0647\u0627\u0648\u0628\u064a\u0646\u0627\u0644\u0625\u062f\u0627\u0631\u0629\u0627\u0644\u062a\u0642\u0644\u064a\u062f\u064a\u0629.<\/li>\n<li>\u0645\u0639\u0631\u0641 \u0623\u0647\u0645\u064a\u0629\u0627\u0633\u062a\u062e\u062f\u0627\u0645\u0627\u0644\u0627\u062f\u0627\u0631\u0629\u0627\u0644\u0627\u0643\u062a\u0631\u0648\u0646\u064a\u0629\u0641\u064a\u0627\u0644\u0639\u0635\u0631\u0627\u0644\u062d\u0627\u0644\u064a\u0648\u0627\u0644\u062d\u0627\u062c\u0629\u0644\u0644\u0627\u0646\u062a\u0642\u0627\u0644\u0645\u0646\u0627\u0644\u0645\u0646\u0638\u0645\u0627\u062a\u0627\u0644\u062a\u0642\u0644\u064a\u062f\u064a\u0629\u0625\u0644\u0649\u0627\u0644\u0645\u0646\u0638\u0645\u0627\u062a\u0627\u0644\u0631\u0642\u0645\u064a\u0629.<\/li>\n<\/ul>\n<p>\u0627\u0644\u062a\u0639\u0631\u0641\u0639\u0644\u0649\u0622\u0644\u064a\u0629\u062a\u062d\u0642\u064a\u0642\u0627\u0644\u062a\u0645\u064a\u064a\u0632\u0627\u0644\u062a\u0646\u0638\u064a\u0645\u064a\u0628\u064a\u0646\u0627\u0644\u0645\u0646\u0638\u0645\u0627\u062a<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22377\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0637\u0631\u064a\u0642\u0629\u0627\u0644\u062a\u062f\u0631\u064a\u0633 Teaching Strategy\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22377\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2221\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0633\u064a\u0642\u062f\u0645\u0627\u0644\u0645\u0642\u0631\u0631 \u0644\u0644\u0637\u0627\u0644\u0628:<\/p>\n<ul>\n<li>\u0645\u062d\u0627\u0636\u0631\u0627\u062a \u0645\u0646\u0647\u062c\u064a\u0629 \u0646\u0638\u0631\u064a\u0629 \u0648\u0639\u0645\u0644\u064a\u0629.<\/li>\n<li>\u0639\u0631\u0648\u0636 \u062a\u0642\u062f\u064a\u0645\u064a\u0629 \u0645\u062a\u0639\u0644\u0642\u0629 \u0628\u0627\u0644\u0645\u0642\u0631\u0631<\/li>\n<\/ul>\n<p>\u0627\u0644\u0646\u0634\u0627\u0637 \u0648\u0627\u0644\u0645\u0634\u0627\u0631\u0643\u0629 \u0648\u0627\u0644\u0648\u0627\u062c\u0628\u0627\u062a<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22477\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u062a\u0642\u064a\u064a\u0645 Assessment\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22477\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2221\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 (\u0627\u0645\u062a\u062d\u0627\u0646 \u0646\u0635\u0641\u064a\u060c \u0646\u0647\u0627\u0626\u064a \u060c\u0648\u0631\u0642\u0627\u062a \u0639\u0645\u0644) \u0639\u0644\u0649 \u0623\u0646 \u062a\u0643\u0648\u0646 \u0627\u0644\u062f\u0631\u062c\u0627\u062a \u0645\u0642\u0633\u0645\u0629 \u0639\u0644\u064a\u0647\u0646 \u0628\u062d\u0633\u0628 \u0645\u0627 \u064a\u0631\u0627\u0647 \u0627\u0644\u0623\u0633\u062a\u0627\u0630 \u0645\u0646\u0627\u0633\u0628 .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-12 m-b30\">\r\n\t\t\t\t\t\t\t<h2 class=\"m-b10 m-t0\">\r\n\t\t\t\t\t\t\t\t\u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<div class=\"dez-accordion space\" id=\"accordionF48C2223\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22186\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0646\u0638\u0631\u0629\u0639\u0627\u0645\u0629\u0639\u0646 \u0627\u0644\u0645\u0642\u0631\u0631 Overview\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22186\" class=\"acod-body collapse show\" data-parent=\"#accordionF48C2223\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u064a\u0634\u0645\u0644 \u0627\u0644\u0645\u0642\u0631\u0631 \u0627\u0644\u062a\u0639\u0631\u064a\u0641 \u0628\u0631\u0623\u064a \u0627\u0644\u0625\u0633\u0644\u0627\u0645 \u0641\u064a \u0645\u0639\u0638\u0645 \u0627\u0644\u0642\u0636\u0627\u064a\u0627 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0629 \u0648\u0645\u0642\u0627\u0631\u0646\u062a\u0647\u0627 \u0645\u0639 \u0645\u0639\u0638\u0645 \u0627\u0644\u0646\u0638\u0645 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0629 \u0627\u0644\u0623\u062e\u0631\u0649<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22286\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u0645\u062e\u0631\u062c\u0627\u062a \u0627\u0644\u062a\u0639\u0644\u064a\u0645\u064a\u0629 (ILOs)\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22286\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2223\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0627\u0644\u062a\u0639\u0631\u064a\u0641 \u0628\u0639\u0644\u0645 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u060c \u0627\u0644\u062a\u0639\u0631\u064a\u0641 \u0628\u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a \u0648\u0623\u0647\u062f\u0627\u0641\u0647 \u0648\u0645\u0628\u0627\u062f\u0626\u0647\u060c \u0648\u0625\u0639\u0637\u0627\u0621 \u0645\u0641\u0627\u0647\u064a\u0645 \u0639\u0627\u0645\u0629 \u0639\u0646 \u0627\u0644\u0641\u0643\u0631 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a \u0627\u0644\u0648\u0636\u0639\u064a \u0644\u0645\u0642\u0627\u0631\u0646\u062a\u0647\u0627 \u0645\u0639 \u0627\u0644\u0641\u0643\u0631 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u060c \u0648\u0627\u0644\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0627\u0644\u0645\u0634\u0643\u0644\u0629 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0629 \u0641\u064a \u0627\u0644\u0646\u0638\u0627\u0645 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a \u0648\u0643\u064a\u0641 \u0623\u0648\u062c\u062f \u0627\u0644\u0625\u0633\u0644\u0627\u0645 \u0639\u0646 \u0623\u0647\u0645 \u0627\u0644\u062d\u0644\u0648\u0644 \u0644\u0647\u062f\u0647 \u0627\u0644\u0645\u0634\u0627\u0643\u0644\u060c \u062f\u0631\u0627\u0633\u0629 \u0627\u0644\u0645\u0627\u0644\u064a\u0629 \u0627\u0644\u0639\u0627\u0645\u0629 \u0641\u064a \u0627\u0644\u0641\u0643\u0631 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u060c \u0627\u0644\u062a\u0639\u0631\u064a\u0641 \u0628\u0645\u0641\u0647\u0648\u0645 \u0627\u0644\u062a\u0646\u0645\u064a\u0629 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0629 \u0641\u064a \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u060c \u0648\u0646\u0642\u062f \u0648\u062a\u062d\u0644\u064a\u0644 \u0627\u0644\u0623\u0633\u0633 \u0627\u0644\u0646\u0638\u0631\u064a\u0629 \u0644\u0644\u0627\u0642\u062a\u0635\u0627\u062f \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a \u0648\u0645\u062d\u0627\u0648\u0644\u0647 \u0627\u0644\u0645\u0642\u0627\u0631\u0646\u0629 \u0628\u064a\u0646 \u0627\u0644\u0646\u0638\u0631\u064a\u0629 \u0648\u0627\u0644\u062a\u0637\u0628\u064a\u0642.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22386\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0637\u0631\u064a\u0642\u0629\u0627\u0644\u062a\u062f\u0631\u064a\u0633 Teaching Strategy\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22386\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2223\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>1\u00a0 \u0627\u0644\u0645\u062d\u0627\u0636\u0631\u0627\u062a \u0627\u0644\u062f\u0631\u0627\u0633\u064a\u0629 .<\/p>\n<p>2 \u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 .<\/p>\n<p>3\u00a0 \u0627\u0639\u062f\u0627\u062f \u0627\u0648\u0631\u0627\u0642 \u0628\u062d\u062b\u064a\u0629 \u0648\u0645\u0646\u0627\u0642\u0634\u062a\u0647\u0627 .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22486\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u062a\u0642\u064a\u064a\u0645 Assessment\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22486\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2223\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u062a\u062a\u0645 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0639\u0645\u0644 \u0627\u0645\u062a\u062d\u0627\u0646 \u062a\u062d\u0631\u064a\u0631\u064a \u0646\u0635\u0641\u0649\u060c \u0648\u0634\u0641\u0648\u064a\u060c \u0648\u0648\u0627\u062c\u0628 \u062f\u0631\u0627\u0633\u064a\u060c \u0648\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 \u0648\u0627\u0645\u062a\u062d\u0627\u0646 \u0646\u0647\u0627\u0626\u0649. .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-12 m-b30\">\r\n\t\t\t\t\t\t\t<h2 class=\"m-b10 m-t0\">\r\n\t\t\t\t\t\t\t\t\u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f \u0627\u0644\u0642\u064a\u0627\u0633\u064a 1\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<div class=\"dez-accordion space\" id=\"accordionF48C2227\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22185\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0646\u0638\u0631\u0629\u0639\u0627\u0645\u0629\u0639\u0646 \u0627\u0644\u0645\u0642\u0631\u0631 Overview\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22185\" class=\"acod-body collapse show\" data-parent=\"#accordionF48C2227\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u064a\u0634\u0645\u0644 \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0631\u0631 \u0645\u0642\u062f\u0645\u0629 \u0641\u064a \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f \u0627\u0644\u0642\u064a\u0627\u0633\u064a \u0645\u0646 \u062d\u064a\u062b \u0627\u0644\u0645\u0641\u0647\u0648\u0645 \u0648\u0637\u0631\u0642 \u0627\u0644\u062a\u0642\u062f\u064a\u0631 \u0648\u0627\u0644\u062a\u0642\u064a\u064a\u0645 .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22285\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u0645\u062e\u0631\u062c\u0627\u062a \u0627\u0644\u062a\u0639\u0644\u064a\u0645\u064a\u0629 (ILOs)\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22285\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2227\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u062a\u0645\u0643\u064a\u0646 \u0627\u0644\u0637\u0627\u0644\u0628 \u0645\u0646 \u062a\u0637\u0628\u064a\u0642 \u0627\u0644\u0646\u0645\u0627\u0630\u062c \u0627\u0644\u0642\u064a\u0627\u0633\u064a\u0629 \u0639\u0644\u0649 \u0628\u064a\u0627\u0646\u0627\u062a \u0648\u0627\u0642\u0639\u064a\u0629\u060c \u062a\u0632\u0648\u064a\u062f \u0627\u0644\u0637\u0627\u0644\u0628 \u0628\u0627\u0644\u0645\u0639\u0627\u0631\u0641 \u0627\u0644\u0623\u062f\u0648\u0627\u062a \u0627\u0644\u0625\u062d\u0635\u0627\u0626\u064a\u0629 \u0648\u0627\u0644\u0631\u064a\u0627\u0636\u064a\u0629 \u0627\u0644\u0644\u0627\u0632\u0645\u0629 \u0644\u062a\u062d\u0644\u064a\u0644 \u0627\u0644\u0645\u062a\u063a\u064a\u0631\u0627\u062a \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0629\u060c \u0637\u0631\u0642 \u062a\u0642\u062f\u064a\u0631 \u0627\u0644\u0645\u062c\u0627\u0647\u064a\u0644 \u0641\u064a \u0627\u0644\u0646\u0645\u0627\u0630\u062c \u0627\u0644\u0642\u064a\u0627\u0633\u064a\u0629\u060c \u0627\u0644\u062a\u0646\u0628\u0624 \u0628\u0627\u0644\u0645\u0633\u0627\u0631 \u0627\u0644\u0632\u0645\u0646\u064a \u0644\u0642\u064a\u0645 \u0627\u0644\u0645\u062a\u063a\u064a\u0631\u0627\u062a \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0629\u060c \u062a\u0632\u0648\u064a\u062f \u0627\u0644\u0637\u0627\u0644\u0628 \u0628\u0627\u0644\u0645\u0639\u0627\u0631\u0641 \u0627\u0644\u062e\u0627\u0635\u0629 \u0628\u0637\u0631\u0642 \u0635\u064a\u0627\u063a\u0629 \u0627\u0644\u0646\u0645\u0627\u0630\u062c \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0629 \u0648\u0637\u0631\u0642 \u0642\u064a\u0627\u0633 \u0627\u0644\u0645\u062a\u063a\u064a\u0631\u0627\u062a \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0629 \u0648\u0627\u0644\u062a\u0646\u0628\u0624 \u0628\u0642\u064a\u0645\u0647\u0627<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22385\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0637\u0631\u064a\u0642\u0629\u0627\u0644\u062a\u062f\u0631\u064a\u0633 Teaching Strategy\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22385\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2227\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>1 \u0627\u0644\u0645\u062d\u0627\u0636\u0631\u0627\u062a \u0627\u0644\u062f\u0631\u0627\u0633\u064a\u0629 .<\/p>\n<p>2 \u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 .<\/p>\n<p>3 \u0627\u0639\u062f\u0627\u062f \u0627\u0648\u0631\u0627\u0642 \u0628\u062d\u062b\u064a\u0629 \u0648\u0645\u0646\u0627\u0642\u0634\u062a\u0647\u0627 .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22485\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u062a\u0642\u064a\u064a\u0645 Assessment\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22485\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2227\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u062a\u062a\u0645 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0639\u0645\u0644 \u0627\u0645\u062a\u062d\u0627\u0646 \u062a\u062d\u0631\u064a\u0631\u064a \u0646\u0635\u0641\u0649\u060c \u0648\u0634\u0641\u0648\u064a\u060c \u0648\u0648\u0627\u062c\u0628 \u062f\u0631\u0627\u0633\u064a\u060c \u0648\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 \u0648\u0627\u0645\u062a\u062d\u0627\u0646 \u0646\u0647\u0627\u0626\u0649. .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-12 m-b30\">\r\n\t\t\t\t\t\t\t<h2 class=\"m-b10 m-t0\">\r\n\t\t\t\t\t\t\t\t\u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f \u0627\u0644\u0642\u064a\u0627\u0633\u064a 2\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<div class=\"dez-accordion space\" id=\"accordionF48C2228\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22184\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0646\u0638\u0631\u0629\u0639\u0627\u0645\u0629\u0639\u0646 \u0627\u0644\u0645\u0642\u0631\u0631 Overview\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22184\" class=\"acod-body collapse show\" data-parent=\"#accordionF48C2228\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u064a\u0634\u0645\u0644 \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0631\u0631 \u0627\u0644\u0646\u0645\u0627\u0630\u062c \u0627\u0644\u0645\u062a\u0642\u062f\u0645\u0629 \u0641\u064a \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f \u0627\u0644\u0642\u064a\u0627\u0633\u064a \u0645\u062b\u0644 \u0627\u0644\u0645\u0639\u0627\u062f\u0644\u0627\u062a \u0627\u0644\u0622\u0646\u064a\u0629 \u0648\u0627\u0644\u062a\u0628\u0627\u0637\u0624\u0627\u062a \u0627\u0644\u0632\u0645\u0646\u064a\u0629 \u0648\u0627\u062e\u062a\u0628\u0627\u0631\u0627\u062a \u0627\u0644\u0633\u0644\u0627\u0633\u0644 \u0627\u0644\u0632\u0645\u0646\u064a\u0629 \u0648\u0627\u062e\u062a\u0628\u0627\u0631\u0627\u062a \u0627\u0644\u0633\u0628\u0628\u064a\u0629 \u0648\u0646\u0645\u0627\u0630\u062c \u062a\u0635\u062d\u064a\u062d \u0627\u0644\u062e\u0637\u0623.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22284\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u0645\u062e\u0631\u062c\u0627\u062a \u0627\u0644\u062a\u0639\u0644\u064a\u0645\u064a\u0629 (ILOs)\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22284\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2228\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0627\u0644\u0627\u0633\u062a\u0641\u0627\u062f\u0629 \u0645\u0646 \u0639\u0645\u0644\u064a\u0629 \u0627\u0644\u062c\u0645\u0639 \u0627\u0644\u062d\u0627\u0635\u0644\u0629 \u0628\u064a\u0646 \u0627\u0644\u0646\u0638\u0631\u064a\u0629 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0629 \u0648\u0627\u0644\u0623\u0633\u0627\u0644\u064a\u0628 \u0627\u0644\u0625\u062d\u0635\u0627\u0626\u064a\u0629\u060c \u0627\u0644\u0627\u0633\u062a\u0639\u0627\u0646\u0629 \u0628\u0627\u0644\u0637\u0631\u0642 \u0627\u0644\u0625\u062d\u0635\u0627\u0626\u064a\u0629 \u0644\u0644\u062d\u0635\u0648\u0644 \u0639\u0644\u0649 \u062a\u0642\u062f\u064a\u0631\u0627\u062a \u0643\u0645\u064a\u0629 \u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645\u0647\u0627 \u0641\u064a \u0639\u0645\u0644\u064a\u0629 \u0627\u062a\u062e\u0627\u0630 \u0627\u0644\u0642\u0631\u0627\u0631\u060c \u062f\u0631\u0627\u0633\u0629 \u0627\u0644\u062a\u063a\u064a\u0631\u0627\u062a \u0627\u0644\u0647\u064a\u0643\u0644\u064a\u0629.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22384\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0637\u0631\u064a\u0642\u0629\u0627\u0644\u062a\u062f\u0631\u064a\u0633 Teaching Strategy\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22384\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2228\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>1. \u0627\u0644\u0645\u062d\u0627\u0636\u0631\u0627\u062a \u0627\u0644\u062f\u0631\u0627\u0633\u064a\u0629 .<\/p>\n<p>2.\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 .<\/p>\n<p>.3\u0627\u0639\u062f\u0627\u062f \u0627\u0648\u0631\u0627\u0642 \u0628\u062d\u062b\u064a\u0629 \u0648\u0645\u0646\u0627\u0642\u0634\u062a\u0647\u0627 .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22484\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u062a\u0642\u064a\u064a\u0645 Assessment\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22484\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2228\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u062a\u062a\u0645 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0639\u0645\u0644 \u0627\u0645\u062a\u062d\u0627\u0646 \u062a\u062d\u0631\u064a\u0631\u064a \u0646\u0635\u0641\u0649\u060c \u0648\u0634\u0641\u0648\u064a\u060c \u0648\u0648\u0627\u062c\u0628 \u062f\u0631\u0627\u0633\u064a\u060c \u0648\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 \u0648\u0627\u0645\u062a\u062d\u0627\u0646 \u0646\u0647\u0627\u0626\u0649. .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-12 m-b30\">\r\n\t\t\t\t\t\t\t<h2 class=\"m-b10 m-t0\">\r\n\t\t\t\t\t\t\t\t\u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f \u0627\u0644\u0643\u0644\u064a 1\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<div class=\"dez-accordion space\" id=\"accordionF48C2230\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22188\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0646\u0638\u0631\u0629 \u0639\u0627\u0645\u0629 \u0639\u0646 \u0627\u0644\u0645\u0642\u0631\u0631 Overview\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22188\" class=\"acod-body collapse show\" data-parent=\"#accordionF48C2230\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0645\u0642\u0631\u0631 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f \u0627\u0644\u0643\u0644\u064a1 \u0645\u0646 \u0627\u0644\u0645\u0642\u0631\u0631\u0627\u062a \u0627\u0644\u0645\u0647\u0645\u0629 \u0644\u0644\u0637\u0627\u0644\u0628 \u0641\u064a \u0645\u0639\u0631\u0641\u0629 \u0643\u0644 \u062c\u0648\u0627\u0646\u0628 \u0648\u0642\u0636\u0627\u064a\u0627 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f \u0627\u0644\u0643\u0644\u064a \u0648\u0627\u064a\u0636\u0627 \u0627\u0644\u062a\u0648\u0633\u0639 \u0641\u064a \u0645\u0639\u0631\u0641\u0629 \u0648\u0641\u0647\u0645 \u0627\u0644\u0645\u0634\u0643\u0644\u0627\u062a \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0629 \u0648\u0627\u0644\u0646\u0638\u0631\u064a\u0627\u062a \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0629 \u0627\u0644\u062a\u064a \u0639\u0627\u0644\u062c\u062a \u0647\u0630\u0647 \u0627\u0644\u0645\u0634\u0643\u0644\u0627\u062a \u0648\u0627\u064a\u0636\u0627 \u062a\u0632\u0648\u064a\u062f \u0627\u0644\u0637\u0627\u0644\u0628 \u0628\u0627\u0644\u0627\u062f\u0648\u0627\u062a \u0627\u0644\u0627\u0632\u0645\u0629 \u0627\u0644\u0645\u0633\u0627\u0639\u062f\u0629 \u0639\u0644\u064a \u0627\u0644\u062a\u062d\u0644\u064a\u0644 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22288\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u0645\u062e\u0631\u062c\u0627\u062a \u0627\u0644\u062a\u0639\u0644\u064a\u0645\u064a\u0629 (ILOs)\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22288\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2230\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u064a\u0645\u0643\u0646\u0647\u0645 \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0631\u0631 \u0645\u0646 \u0645\u0639\u0631\u0641\u0647 \u0627\u0644\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u064a \u064a\u0633\u062a\u0637\u064a\u0639\u0648\u0646 \u0628\u0647\u0627 \u062f\u0631\u0627\u0633\u0629 \u0648\u0645\u0639\u0631\u0641\u0647 \u0627\u0644\u0645\u0634\u0643\u0644\u0627\u062a \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0629 \u0648\u0627\u0644\u0645\u0633\u0627\u0647\u0645\u0629 \u0641\u064a \u062d\u0644 \u0647\u0630\u0647 \u0627\u0644\u0645\u0634\u0643\u0644\u0627\u062a \u0628\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0627\u0644\u062a\u062d\u0627\u0644\u064a\u0644 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0629 \u0627\u0644\u0645\u0646\u0627\u0633\u0628\u0629 \u0627\u0644\u0645\u0639\u062a\u0645\u062f\u0629 \u0639\u0644\u064a \u0627\u0644\u0646\u0638\u0631\u064a\u0627\u062a \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0629 \u00a0\u060c \u0648\u0643\u0630\u0644\u0643 \u062a\u0639\u0631\u0641\u0647\u0645 \u0639\u0644\u0649 \u0627\u0646\u0633\u0628 \u0627\u0644\u0637\u0631\u0642 \u0644\u062a\u062c\u0646\u0628 \u0647\u0630\u0647 \u0627\u0644\u0645\u0634\u0627\u0643\u0644 .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22388\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u062f\u0631\u064a\u0633 Teaching Strategy\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22388\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2230\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>1.\u0627\u0644\u0645\u062d\u0627\u0636\u0631\u0627\u062a \u0627\u0644\u062f\u0631\u0627\u0633\u064a\u0629 .<\/p>\n<p>2.\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 .<\/p>\n<p>3.\u0627\u0639\u062f\u0627\u062f \u0627\u0648\u0631\u0627\u0642 \u0628\u062d\u062b\u064a\u0629 \u0648\u0645\u0646\u0627\u0642\u0634\u062a\u0647\u0627<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22488\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u062a\u0642\u064a\u064a\u0645 Assessment\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22488\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2230\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u062a\u062a\u0645 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0639\u0645\u0644 \u0627\u0645\u062a\u062d\u0627\u0646 \u062a\u062d\u0631\u064a\u0631\u064a\u060c \u0648\u0634\u0641\u0648\u064a\u060c \u0648\u0648\u0627\u062c\u0628 \u062f\u0631\u0627\u0633\u064a\u060c \u0648\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-12 m-b30\">\r\n\t\t\t\t\t\t\t<h2 class=\"m-b10 m-t0\">\r\n\t\t\t\t\t\t\t\t\u0627\u0644\u062a\u062e\u0637\u064a\u0637 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<div class=\"dez-accordion space\" id=\"accordionF48C2233\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22183\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0646\u0638\u0631\u0629\u0639\u0627\u0645\u0629\u0639\u0646 \u0627\u0644\u0645\u0642\u0631\u0631 Overview\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22183\" class=\"acod-body collapse show\" data-parent=\"#accordionF48C2233\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0645\u0627\u0647\u064a\u0629 \u0648\u0645\u0641\u0647\u0648\u0645 \u0627\u0644\u062a\u062e\u0637\u064a\u0637 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a \u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u062a\u062e\u0637\u064a\u0637 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a \u0645\u062c\u0627\u0644\u0627\u062a \u0627\u0644\u062a\u062e\u0637\u064a\u0637 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a \u0646\u0645\u0627\u0630\u062c \u0631\u064a\u0627\u0636\u064a\u0629 \u062a\u0637\u0628\u064a\u0642\u064a\u0629 \u0639\u0646 \u0627\u0644\u062a\u062e\u0637\u064a\u0637 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a \u0622\u0644\u064a\u0629 \u0625\u0639\u062f\u0627\u062f \u0627\u0644\u062e\u0637\u0637 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0629.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22283\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u0645\u062e\u0631\u062c\u0627\u062a \u0627\u0644\u062a\u0639\u0644\u064a\u0645\u064a\u0629(ILOs)\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22283\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2233\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u062a\u0639\u0631\u064a\u0641 \u0627\u0644\u0637\u0644\u0627\u0628 \u0623\u0647\u0645\u064a\u0629 \u0627\u0644\u062a\u062e\u0637\u064a\u0637 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a \u0627\u0644\u0630\u064a \u064a\u062a\u0645\u062b\u0644 \u0641\u064a \u062a\u062d\u0642\u064a\u0642 \u0623\u0647\u062f\u0627\u0641 \u0627\u0644\u062a\u0646\u0645\u064a\u0629 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0629 \u0627\u0644\u0645\u062a\u0648\u0627\u0632\u0646\u0629 \u0645\u0646 \u062e\u0644\u0627\u0644 \u0646\u0638\u0631\u0629 \u0645\u0633\u062a\u0642\u0628\u0644\u064a\u0629 \u0648\u062a\u062d\u0642\u064a\u0642 \u0627\u0644\u062a\u0648\u0627\u0632\u0646 \u0627\u0644\u0643\u0644\u064a \u0648\u0627\u0644\u062a\u0648\u0627\u0632\u0646 \u0627\u0644\u062c\u0632\u0626\u064a \u062a\u0639\u0631\u064a\u0641 \u0627\u0644\u0637\u0627\u0644\u0628 \u0628\u0627\u0644\u062a\u062e\u0637\u064a\u0637 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a \u0648\u0645\u0628\u0631\u0631\u0627\u062a\u0647 \u0648\u0645\u0631\u0627\u062d\u0644 \u062a\u0637\u0648\u0631\u0647\u060c \u0648\u0627\u0644\u0623\u0633\u0627\u0644\u064a\u0628 \u0627\u0644\u0645\u0633\u062a\u062e\u062f\u0645\u0629 \u0641\u064a \u0627\u0644\u0639\u0645\u0644\u064a\u0629 \u0627\u0644\u062a\u062e\u0637\u064a\u0637\u064a\u0629 \u0645\u0639\u0631\u0641\u0629 \u0643\u064a\u0641\u064a\u0647 \u0648\u0636\u0639 \u0627\u0644\u062e\u0637\u0637 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0629 \u0648\u0645\u062a\u0627\u0628\u0639\u062a\u0647\u0627.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22383\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0637\u0631\u064a\u0642\u0629\u0627\u0644\u062a\u062f\u0631\u064a\u0633 Teaching Strategy\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22383\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2233\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>1.\u00a0 \u00a0\u0627\u0644\u0645\u062d\u0627\u0636\u0631\u0627\u062a \u0627\u0644\u062f\u0631\u0627\u0633\u064a\u0629<\/p>\n<p>2.\u00a0 \u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 .<\/p>\n<p>3. \u0627\u0639\u062f\u0627\u062f \u0627\u0648\u0631\u0627\u0642 \u0628\u062d\u062b\u064a\u0629 \u0648\u0645\u0646\u0627\u0642\u0634\u062a\u0647\u0627<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22483\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u062a\u0642\u064a\u064a\u0645Assessment\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22483\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2233\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u062a\u062a\u0645 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0639\u0645\u0644 \u0627\u0645\u062a\u062d\u0627\u0646 \u062a\u062d\u0631\u064a\u0631\u064a \u0646\u0635\u0641\u0649\u060c \u0648\u0634\u0641\u0648\u064a\u060c \u0648\u0648\u0627\u062c\u0628 \u062f\u0631\u0627\u0633\u064a\u060c \u0648\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 \u0648\u0627\u0645\u062a\u062d\u0627\u0646 \u0646\u0647\u0627\u0626\u0649. .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-12 m-b30\">\r\n\t\t\t\t\t\t\t<h2 class=\"m-b10 m-t0\">\r\n\t\t\t\t\t\t\t\t\u0627\u0644\u0645\u062d\u0627\u0633\u0628\u0629 \u0627\u0644\u0636\u0631\u064a\u0628\u064a\u0629\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<div class=\"dez-accordion space\" id=\"accordionF48C2242\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22193\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0646\u0638\u0631\u0629\u0639\u0627\u0645\u0629\u0639\u0646 \u0627\u0644\u0645\u0642\u0631\u0631 Overview\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22193\" class=\"acod-body collapse show\" data-parent=\"#accordionF48C2242\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u064a\u0634\u0645\u0644 \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0631\u0631 \u0639\u0644\u0649 \u062a\u0639\u0631\u064a\u0641 \u0627\u0644\u0636\u0631\u064a\u0628\u0629 \u0648\u0627\u0644\u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0644\u0636\u0631\u0627\u0626\u0628 \u0648\u0643\u064a\u0641\u064a\u0629 \u062d\u0633\u0627\u0628 \u0627\u0644\u0636\u0631\u064a\u0628\u0629 \u0648\u0631\u0628\u0637\u0647\u0627 \u0648\u0645\u0648\u0639\u062f \u0627\u0633\u062a\u062d\u0642\u0627\u0642\u0647\u0627 \u0648\u0643\u064a\u0641\u064a\u0629 \u062d\u0633\u0627\u0628 \u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0636\u0631\u0627\u0626\u0628 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0645\u0646 \u0635\u0627\u0641\u064a \u0627\u0644\u062f\u062e\u0644 \u0627\u0644\u0636\u0631\u064a\u0628\u0629 \u0639\u0644\u0649 \u062f\u062e\u0644 \u0627\u0644\u0645\u0647\u0646 \u0627\u0644\u062d\u0631\u0629 \u0648\u0627\u0644\u0636\u0631\u064a\u0628\u0629 \u0639\u0644\u0649 \u062f\u062e\u0644 .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22293\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u0645\u062e\u0631\u062c\u0627\u062a \u0627\u0644\u062a\u0639\u0644\u064a\u0645\u064a\u0629 (ILOs)\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22293\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2242\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u062a\u0639\u0631\u064a\u0641 \u0627\u0644\u0637\u0627\u0644\u0628 \u064a\u0627\u0644\u0623\u0633\u0633 \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u064a\u0629 \u0644\u0644\u0636\u0631\u0627\u0626\u0628 \u062a\u0639\u0631\u064a\u0641 \u0627\u0644\u0637\u0627\u0644\u0628 \u0628\u0627\u0644\u0646\u0638\u0627\u0645 \u0627\u0644\u0636\u0631\u064a\u0628\u064a \u0641\u064a \u0644\u064a\u0628\u064a\u0627 \u0627\u0644\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0643\u064a\u0641\u064a\u0629 \u0627\u0644\u0645\u0639\u0627\u0644\u062c\u0629 \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u064a\u0629 \u0644\u0644\u0636\u0631\u0627\u0626\u0628 \u0648\u0641\u0642\u0627 \u0644\u0644\u062a\u0634\u0631\u064a\u0639 \u0627\u0644\u0636\u0631\u064a\u0628\u064a \u0627\u0644\u0644\u064a\u0628\u064a \u0627\u0644\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0643\u064a\u0641\u064a\u0629 \u062d\u0633\u0627\u0628 \u0627\u0644\u0636\u0631\u0627\u0626\u0628 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0645\u0646 \u0635\u0627\u0641\u064a \u0627\u0644\u062f\u062e\u0644 \u0627\u0644\u062e\u0627\u0636\u0639 \u0644\u0644\u0636\u0631\u064a\u0628\u0629.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22393\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0637\u0631\u064a\u0642\u0629\u0627\u0644\u062a\u062f\u0631\u064a\u0633 Teaching Strategy\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22393\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2242\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>1.\u0627\u0644\u0645\u062d\u0627\u0636\u0631\u0627\u062a \u0627\u0644\u062f\u0631\u0627\u0633\u064a\u0629<\/p>\n<p>2.\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 .<\/p>\n<p>3.\u0627\u0639\u062f\u0627\u062f \u0627\u0648\u0631\u0627\u0642 \u0628\u062d\u062b\u064a\u0629 \u0648\u0645\u0646\u0627\u0642\u0634\u062a\u0647\u0627<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22493\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u062a\u0642\u064a\u064a\u0645 Assessment\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22493\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2242\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u062a\u062a\u0645 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0639\u0645\u0644 \u0627\u0645\u062a\u062d\u0627\u0646 \u062a\u062d\u0631\u064a\u0631\u064a \u0646\u0635\u0641\u0649\u060c \u0648\u0634\u0641\u0648\u064a\u060c \u0648\u0648\u0627\u062c\u0628 \u062f\u0631\u0627\u0633\u064a\u060c \u0648\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 \u0648\u0627\u0645\u062a\u062d\u0627\u0646 \u0646\u0647\u0627\u0626\u0649. .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-12 m-b30\">\r\n\t\t\t\t\t\t\t<h2 class=\"m-b10 m-t0\">\r\n\t\t\t\t\t\t\t\t\u0627\u0644\u0645\u062d\u0627\u0633\u0628\u0629\u0627\u0644\u062f\u0648\u0644\u064a\u0629\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<div class=\"dez-accordion space\" id=\"accordionF48C2246\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22194\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0646\u0638\u0631\u0629\u0639\u0627\u0645\u0629\u0639\u0646 \u0627\u0644\u0645\u0642\u0631\u0631 Overview\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22194\" class=\"acod-body collapse show\" data-parent=\"#accordionF48C2246\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0647\u062f\u0641 \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0631\u0631 \u0625\u0644\u0649 \u0625\u0643\u0633\u0627\u0628 \u0627\u0644\u0637\u0627\u0644\u0628 \u0645\u0639\u0627\u0631\u0641 \u0648\u0645\u0647\u0627\u0631\u0627\u062a \u0641\u064a \u0645\u062c\u0627\u0644 \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u064a\u0629<br \/>\n\u0641\u064a \u0627\u062a\u062e\u0627\u0630 \u0627\u0644\u0642\u0631\u0627\u0631\u0627\u062a \u0627\u0644\u0625\u062f\u0627\u0631\u064a\u0629. \u0647\u0630\u0647 \u0627\u0644\u0642\u0631\u0627\u0631\u0627\u062a \u062a\u062a\u062e\u0630 \u0639\u0627\u062f\u0629 \u0628\u0646\u0627\u0621\u064b \u0639\u0644\u0649 \u0648\u062c\u0648\u062f \u0645\u062c\u0645\u0648\u0639\u0629 \u0645\u0646 \u0627\u0644\u0628\u062f\u0627\u0626\u0644<br \/>\n\u0627\u0644\u0645\u062a\u0627\u062d\u0629. \u062d\u064a\u062b \u062a\u0639\u0645\u0644 \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u0629 \u0627\u0644\u0625\u062f\u0627\u0631\u064a\u0629 \u0639\u0644\u0649 \u062a\u0642\u062f\u064a\u0645 \u0627\u0644\u0645\u0633\u0627\u0639\u062f\u0629 \u0641\u064a \u062d\u0627\u0644 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0645\u0634\u0627\u0643\u0644 \u0627\u0644\u062a\u064a<br \/>\n\u062a\u0648\u0627\u062c\u0647\u0647\u0627 \u0645\u0646\u0638\u0645\u0627\u062a \u0627\u0644\u0623\u0639\u0645\u0627\u0644 \u0627\u0633\u062a\u0646\u0627\u062f\u0627\u064b \u0625\u0644\u0649 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0633\u0627\u0644\u064a\u0628 \u0648\u0627\u0644\u0623\u062f\u0648\u0627\u062a \u0627\u0644\u062a\u064a \u062a\u062a\u0641\u0631\u062f \u0628\u0647\u0627 \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u0629<br \/>\n\u0627\u0644\u0625\u062f\u0627\u0631\u064a\u0629\u060c \u0644\u0627\u0633\u064a\u0645\u0627 \u062a\u0644\u0643 \u0627\u0644\u0645\u062a\u0639\u0644\u0642\u0629 \u0628\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u062a\u062d\u0644\u064a\u0644\u0627\u062a \u0627\u0644\u062a\u0639\u0627\u062f\u0644 \u0627\u0644\u0645\u0631\u062a\u0628\u0637 \u0623\u0633\u0627\u0633\u0627\u064b \u0639\u0644\u0649 \u0627\u0644\u062a\u0645\u064a\u064a\u0632 \u0628\u064a\u0646 \u0627\u0644\u062a\u0643\u0627\u0644\u064a\u0641 \u0627\u0644\u062b\u0627\u0628\u062a\u0629 \u0648\u0627\u0644\u0645\u062a\u063a\u064a\u0631\u0629 \u0641\u064a \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0645\u062c\u0627\u0644\u0627\u062a \u0645\u062b\u0644 \u062a\u062e\u0637\u064a\u0637 \u0627\u0644\u0645\u0628\u064a\u0639\u0627\u062a\u060c \u0623\u0648 \u0627\u0644\u0631\u0627\u0641\u0639\u0629 \u0627\u0644\u062a\u0634\u063a\u064a\u0644\u064a\u0629. \u0643\u0645\u0627 \u064a\u0633\u0627\u0639\u062f \u0627\u0644\u0645\u0642\u0631\u0631 \u0641\u064a \u062a\u0623\u0635\u064a\u0644 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0637\u0631 \u0627\u0644\u0645\u062a\u0639\u0644\u0642\u0629 \u0628\u062a\u062e\u0637\u064a\u0637 \u0627\u0644\u0625\u0646\u062a\u0627\u062c \u0648\u0627\u0644\u0623\u0631\u0628\u0627\u062d \u0641\u064a \u0627\u0644\u0623\u062c\u0644 \u0627\u0644\u0642\u0635\u064a\u0631\u060c \u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u062f\u0648\u0631 \u0627\u0644\u0645\u0648\u0627\u0632\u0646\u0627\u062a \u0627\u0644\u062a\u062e\u0637\u064a\u0637\u064a\u0629 \u0641\u064a \u0639\u0645\u0644\u064a\u0629 \u0627\u0644\u0631\u0642\u0627\u0628\u0629 \u0648\u062a\u0642\u0644\u064a\u0644 \u0627\u0644\u0647\u062f\u0631 \u0648\u0627\u0644\u0641\u0627\u0642\u062f \u0641\u064a \u0623\u0648\u062c\u0647 \u0627\u0644\u0646\u0634\u0627\u0637 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629\u060c \u0648\u0623\u062e\u064a\u0631\u0627\u064b \u062a\u0639\u0644\u064a\u0645 \u0627\u0644\u0637\u0627\u0644\u0628 \u0643\u064a\u0641\u064a\u0629 \u0625\u0639\u062f\u0627\u062f \u062a\u0642\u0627\u0631\u064a\u0631 \u0627\u0644\u0623\u062f\u0627\u0621 \u0628\u0646\u0627\u0621\u064b \u0639\u0644\u0649 \u0646\u0638\u0627\u0645 \u0627\u0644\u0644\u0627\u0645\u0631\u0643\u0632\u064a\u0629 \u0648\u0645\u062d\u0627\u0633\u0628\u0629 \u0627\u0644\u0645\u0633\u0624\u0648\u0644\u064a\u0629<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22294\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u0645\u062e\u0631\u062c\u0627\u062a \u0627\u0644\u062a\u0639\u0644\u064a\u0645\u064a\u0629 (ILOs)\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22294\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2246\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u064a\u062a\u0630\u0643\u0631 \u0645\u0641\u0627\u0647\u064a\u0645 \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u0629 \u0627\u0644\u0625\u062f\u0627\u0631\u064a\u0629 \u0648\u0623\u0647\u0645\u064a\u062a\u0647\u0627 \u0648\u062f\u0648\u0631\u0647\u0627 \u0648\u0623\u0646 \u064a\u0645\u064a\u0632 \u0628\u064a\u0646\u0647\u0627 \u0648\u0628\u064a\u0646 \u0627\u0644\u0645\u062c\u0627\u0644\u0627\u062a \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u064a\u0629 \u0627\u0644\u0623\u062e\u0631\u0649. \u064a\u062d\u062f\u062f \u0645\u0641\u0647\u0648\u0645 \u0627\u0644\u062a\u0643\u0644\u0641\u0629 \u0648\u062a\u0635\u0646\u064a\u0641\u0627\u062a \u0627\u0644\u062a\u0643\u0627\u0644\u064a\u0641 \u0648\u064a\u0641\u0631\u0642 \u0628\u064a\u0646 \u0627\u0644\u062a\u0643\u0644\u0641\u0629 \u0648\u0627\u0644\u0645\u0635\u0631\u0648\u0641 \u0648\u0627\u0644\u062e\u0633\u0627\u0631\u0629 \u064a\u0645\u064a\u0632 \u0633\u0644\u0648\u0643 \u0639\u0646\u0627\u0635\u0631 \u0627\u0644\u062a\u0643\u0627\u0644\u064a\u0641 \u0627\u0644\u0645\u062a\u0645\u062b\u0644\u0629 \u0628\u0627\u0644\u062a\u0643\u0627\u0644\u064a\u0641 \u0627\u0644\u0645\u062a\u063a\u064a\u0631\u0629 \u0648\u0627\u0644\u062b\u0627\u0628\u062a\u0629 \u0648\u0634\u0628\u0647 \u0627\u0644\u0645\u062a\u063a\u064a\u0631\u0629 \u064a\u0641\u0647\u0645 \u0643\u064a\u0641\u064a\u0629 \u062a\u0633\u0639\u064a\u0631 \u0627\u0644\u0645\u0646\u062a\u062c\u0627\u062a \u0627\u0633\u062a\u0646\u0627\u062f\u0627 \u0625\u0644\u0649 \u0628\u064a\u0627\u0646\u0627\u062a \u0627\u0644\u062a\u0643\u0644\u0641\u0629. \u064a\u0641\u0633\u0631 \u0647\u0627\u0645\u0634 \u0627\u0644\u0645\u0633\u0627\u0647\u0645\u0629 \u0648\u0645\u062f\u0644\u0648\u0644\u0627\u062a\u0647 \u0648\u0623\u0647\u0645\u064a\u062a\u0647 \u0641\u064a \u062a\u062d\u0644\u064a\u0644 \u0627\u0644\u062a\u0639\u0627\u062f\u0644\u060c \u0648\u0627\u0644\u0639\u0648\u0627\u0645\u0644 \u0627\u0644\u062a\u064a \u062a\u0624\u062b\u0631 \u0641\u064a \u062a\u062d\u062f\u064a\u062f\u0647. \u064a\u0633\u062a\u062e\u062f\u0645 \u0645\u0641\u0627\u0647\u064a\u0645 \u062a\u062d\u0644\u064a\u0644 \u0627\u0644\u062a\u0639\u0627\u062f\u0644 \u0641\u064a \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0645\u062c\u0627\u0644\u0627\u062a \u0627\u0644\u0645\u062a\u0639\u0644\u0642\u0629 \u0628\u0627\u062a\u062e\u0627\u0630 \u0627\u0644\u0642\u0631\u0627\u0631\u0627\u062a \u0642\u0635\u064a\u0631\u0629 \u0627\u0644\u0623\u062c\u0644. \u064a\u0641\u0647\u0645 \u0643\u064a\u0641\u064a\u0629 \u0625\u0639\u062f\u0627\u062f \u0627\u0644\u0645\u0648\u0627\u0632\u0646\u0627\u062a \u0627\u0644\u062a\u062e\u0637\u064a\u0637\u064a\u0629. \u064a\u0643\u062a\u0628 \u062a\u0642\u0627\u0631\u064a\u0631 \u0627\u0644\u0623\u062f\u0627\u0621 \u0628\u0646\u0627\u0621\u064b \u0639\u0644\u0649 \u0646\u0638\u0627\u0645 \u0627\u0644\u0644\u0627\u0645\u0631\u0643\u0632\u064a\u0629 \u0648\u0645\u062d\u0627\u0633\u0628\u0629 \u0627\u0644\u0645\u0633\u0624\u0648\u0644\u064a\u0629.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22394\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u062a\u0642\u064a\u064a\u0645 Assessment\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22394\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2246\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u062a\u062a\u0645 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0639\u0645\u0644 \u0627\u0645\u062a\u062d\u0627\u0646 \u062a\u062d\u0631\u064a\u0631\u064a \u0646\u0635\u0641\u0649\u060c \u0648\u0634\u0641\u0648\u064a\u060c \u0648\u0648\u0627\u062c\u0628 \u062f\u0631\u0627\u0633\u064a\u060c \u0648\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 \u0648\u0627\u0645\u062a\u062d\u0627\u0646 \u0646\u0647\u0627\u0626\u0649.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22494\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u0645\u062e\u0631\u062c\u0627\u062a \u0627\u0644\u062a\u0639\u0644\u064a\u0645\u064a\u0629 (ILOs)\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22494\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2246\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u064a\u062a\u0630\u0643\u0631 \u0645\u0641\u0627\u0647\u064a\u0645 \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u0629 \u0627\u0644\u0625\u062f\u0627\u0631\u064a\u0629 \u0648\u0623\u0647\u0645\u064a\u062a\u0647\u0627 \u0648\u062f\u0648\u0631\u0647\u0627 \u0648\u0623\u0646 \u064a\u0645\u064a\u0632 \u0628\u064a\u0646\u0647\u0627 \u0648\u0628\u064a\u0646 \u0627\u0644\u0645\u062c\u0627\u0644\u0627\u062a \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u064a\u0629 \u0627\u0644\u0623\u062e\u0631\u0649. \u064a\u062d\u062f\u062f \u0645\u0641\u0647\u0648\u0645 \u0627\u0644\u062a\u0643\u0644\u0641\u0629 \u0648\u062a\u0635\u0646\u064a\u0641\u0627\u062a \u0627\u0644\u062a\u0643\u0627\u0644\u064a\u0641 \u0648\u064a\u0641\u0631\u0642 \u0628\u064a\u0646 \u0627\u0644\u062a\u0643\u0644\u0641\u0629 \u0648\u0627\u0644\u0645\u0635\u0631\u0648\u0641 \u0648\u0627\u0644\u062e\u0633\u0627\u0631\u0629 \u064a\u0645\u064a\u0632 \u0633\u0644\u0648\u0643 \u0639\u0646\u0627\u0635\u0631 \u0627\u0644\u062a\u0643\u0627\u0644\u064a\u0641 \u0627\u0644\u0645\u062a\u0645\u062b\u0644\u0629 \u0628\u0627\u0644\u062a\u0643\u0627\u0644\u064a\u0641 \u0627\u0644\u0645\u062a\u063a\u064a\u0631\u0629 \u0648\u0627\u0644\u062b\u0627\u0628\u062a\u0629 \u0648\u0634\u0628\u0647 \u0627\u0644\u0645\u062a\u063a\u064a\u0631\u0629 \u064a\u0641\u0647\u0645 \u0643\u064a\u0641\u064a\u0629 \u062a\u0633\u0639\u064a\u0631 \u0627\u0644\u0645\u0646\u062a\u062c\u0627\u062a \u0627\u0633\u062a\u0646\u0627\u062f\u0627 \u0625\u0644\u0649 \u0628\u064a\u0627\u0646\u0627\u062a \u0627\u0644\u062a\u0643\u0644\u0641\u0629. \u064a\u0641\u0633\u0631 \u0647\u0627\u0645\u0634 \u0627\u0644\u0645\u0633\u0627\u0647\u0645\u0629 \u0648\u0645\u062f\u0644\u0648\u0644\u0627\u062a\u0647 \u0648\u0623\u0647\u0645\u064a\u062a\u0647 \u0641\u064a \u062a\u062d\u0644\u064a\u0644 \u0627\u0644\u062a\u0639\u0627\u062f\u0644\u060c \u0648\u0627\u0644\u0639\u0648\u0627\u0645\u0644 \u0627\u0644\u062a\u064a \u062a\u0624\u062b\u0631 \u0641\u064a \u062a\u062d\u062f\u064a\u062f\u0647. \u064a\u0633\u062a\u062e\u062f\u0645 \u0645\u0641\u0627\u0647\u064a\u0645 \u062a\u062d\u0644\u064a\u0644 \u0627\u0644\u062a\u0639\u0627\u062f\u0644 \u0641\u064a \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0645\u062c\u0627\u0644\u0627\u062a \u0627\u0644\u0645\u062a\u0639\u0644\u0642\u0629 \u0628\u0627\u062a\u062e\u0627\u0630 \u0627\u0644\u0642\u0631\u0627\u0631\u0627\u062a \u0642\u0635\u064a\u0631\u0629 \u0627\u0644\u0623\u062c\u0644. \u064a\u0641\u0647\u0645 \u0643\u064a\u0641\u064a\u0629 \u0625\u0639\u062f\u0627\u062f \u0627\u0644\u0645\u0648\u0627\u0632\u0646\u0627\u062a \u0627\u0644\u062a\u062e\u0637\u064a\u0637\u064a\u0629. \u064a\u0643\u062a\u0628 \u062a\u0642\u0627\u0631\u064a\u0631 \u0627\u0644\u0623\u062f\u0627\u0621 \u0628\u0646\u0627\u0621\u064b \u0639\u0644\u0649 \u0646\u0638\u0627\u0645 \u0627\u0644\u0644\u0627\u0645\u0631\u0643\u0632\u064a\u0629 \u0648\u0645\u062d\u0627\u0633\u0628\u0629 \u0627\u0644\u0645\u0633\u0624\u0648\u0644\u064a\u0629.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-12 m-b30\">\r\n\t\t\t\t\t\t\t<h2 class=\"m-b10 m-t0\">\r\n\t\t\t\t\t\t\t\t\u0627\u0644\u0645\u0648\u0627\u0631\u062f \u0627\u0644\u0628\u0634\u0631\u064a\u0629\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<p>\r\n\t\t\t\t\t\t\t\t\u0631\u0645\u0632 \u0627\u0644\u0645\u0642\u0631\u0631: CS223\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<div class=\"dez-accordion space\" id=\"accordionF48C2249\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22168\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0646\u0638\u0631\u0629 \u0639\u0627\u0645\u0629 \u0639\u0646 \u0627\u0644\u0645\u0642\u0631\u0631\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22168\" class=\"acod-body collapse show\" data-parent=\"#accordionF48C2249\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u064a\u062f\u0631\u0633 \u0627\u0644\u0637\u0644\u0627\u0628 \u0641\u064a \u0647\u062f\u0627 \u0627\u0644\u0645\u0642\u0631\u0631 \u0627\u0644\u0645\u0641\u0627\u0647\u064a\u0645 \u0627\u0644\u0623\u0633\u0627\u0633\u064a\u0629 \u0644\u0625\u062f\u0627\u0631\u0629 \u0627\u0644\u0645\u0648\u0627\u0631\u062f \u0627\u0644\u0628\u0634\u0631\u064a\u0629 \u060c \u062a\u062d\u0644\u064a\u0644 \u0648\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0648\u0638\u0627\u0626\u0641 \u060c \u062a\u062e\u0637\u064a\u0637 \u0627\u0644\u0645\u0648\u0627\u0631\u062f \u0627\u0644\u0628\u0634\u0631\u064a\u0629 \u060c \u062a\u0648\u0638\u064a\u0641 \u0627\u0644\u0645\u0648\u0627\u0631\u062f \u0627\u0644\u0628\u0634\u0631\u064a\u0629 \u060c \u0627\u0644\u0627\u062c\u0648\u0631 \u0648\u0627\u0644\u0645\u0631\u062a\u0628\u0627\u062a \u060c \u0646\u0638\u0627\u0645 \u0627\u0644\u0627\u0646\u0636\u0628\u0627\u0637 \u0648\u0627\u0644\u062a\u0623\u062f\u064a\u0628 \u060c \u0627\u0644\u0635\u062d\u0629 \u0648\u0627\u0644\u0633\u0644\u0627\u0645\u0629 \u0627\u0644\u0645\u0647\u0646\u064a\u0629 \u060c \u062a\u0642\u064a\u064a\u0645 \u0627\u062f\u0627\u0621 \u0627\u0644\u0639\u0627\u0645\u0644\u064a\u0646 \u060c \u0627\u0644\u062a\u062f\u0631\u064a\u0628 \u0648\u0627\u0644\u062a\u0646\u0645\u064a\u0629 \u0627\u0644\u0627\u062f\u0627\u0631\u064a\u0629<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22268\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u0645\u062e\u0631\u062c\u0627\u062a \u0627\u0644\u062a\u0639\u0644\u064a\u0645\u064a\u0629\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22268\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2249\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0639\u0646\u062f \u0627\u0644\u0627\u0646\u062a\u0647\u0627\u0621 \u0645\u0646 \u0647\u062f\u0627 \u0627\u0644\u0645\u0642\u0631\u0631 \u0633\u064a\u0643\u0648\u0646 \u0627\u0644\u0637\u0627\u0644\u0628 \u0642\u0627\u062f\u0631\u0627\u064b \u0639\u0644\u0649:<\/p>\n<ul>\n<li>\u0627\u0644\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0627\u0647\u0645 \u0648\u0638\u0627\u0626\u0641 \u0627\u062f\u0627\u0631\u0629 \u0627\u0644\u0645\u0648\u0627\u0631\u062f \u0627\u0644\u0628\u0634\u0631\u064a\u0629<\/li>\n<li>\u0627\u0644\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0645\u0641\u0627\u0647\u064a\u0645 \u0648\u0646\u0638\u0631\u064a\u0627\u062a \u0627\u062f\u0627\u0631\u0629 \u0627\u0644\u0645\u0648\u0627\u0631\u062f \u0627\u0644\u0628\u0634\u0631\u064a\u0629<\/li>\n<li>\u0627\u0643\u062a\u0633\u0627\u0628 \u0627\u0644\u0645\u0647\u0627\u0631\u0627\u062a \u0627\u0644\u0634\u0627\u0645\u0644\u0629 \u0627\u0644\u0645\u062a\u0639\u0644\u0642\u0629 \u0628\u0639\u0644\u0645 \u0625\u062f\u0627\u0631\u0629 \u0627\u0644\u0645\u0648\u0627\u0631\u062f \u0627\u0644\u0628\u0634\u0631\u064a\u0629 .<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22368\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u062f\u0631\u064a\u0633\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22368\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2249\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0633\u064a\u0642\u062f\u0645 \u0627\u0644\u0645\u0642\u0631\u0631 \u0644\u0644\u0637\u0627\u0644\u0628:<\/p>\n<ul>\n<li>\u0645\u062d\u0627\u0636\u0631\u0627\u062a \u0645\u0646\u0647\u062c\u064a\u0629 \u0646\u0638\u0631\u064a\u0629 \u0648\u0639\u0645\u0644\u064a\u0629.<\/li>\n<li>\u0639\u0631\u0648\u0636 \u062a\u0642\u062f\u064a\u0645\u064a\u0629 \u0645\u062a\u0639\u0644\u0642\u0629 \u0628\u0627\u0644\u0645\u0642\u0631\u0631<\/li>\n<li>\u0627\u0644\u0646\u0634\u0627\u0637 \u0648\u0627\u0644\u0645\u0634\u0627\u0631\u0643\u0629 \u0648\u0627\u0644\u0648\u0627\u062c\u0628\u0627\u062a<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22468\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u062a\u0642\u064a\u064a\u0645\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22468\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2249\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 (\u0627\u0645\u062a\u062d\u0627\u0646 \u0646\u0635\u0641\u064a\u060c \u0646\u0647\u0627\u0626\u064a \u060c \u0648\u0631\u0642\u0627\u062a \u0639\u0645\u0644) \u0639\u0644\u0649 \u0623\u0646 \u062a\u0643\u0648\u0646 \u0627\u0644\u062f\u0631\u062c\u0627\u062a \u0645\u0642\u0633\u0645\u0629 \u0639\u0644\u064a\u0647\u0646 \u0628\u062d\u0633\u0628 \u0645\u0627 \u064a\u0631\u0627\u0647 \u0627\u0644\u0623\u0633\u062a\u0627\u0630 \u0645\u0646\u0627\u0633\u0628 ..<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-12 m-b30\">\r\n\t\t\t\t\t\t\t<h2 class=\"m-b10 m-t0\">\r\n\t\t\t\t\t\t\t\t\u062a\u0627\u0631\u064a\u062e \u0627\u0644\u0641\u0643\u0631 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<div class=\"dez-accordion space\" id=\"accordionF48C2254\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22182\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0646\u0638\u0631\u0629\u0639\u0627\u0645\u0629\u0639\u0646 \u0627\u0644\u0645\u0642\u0631\u0631 Overview\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22182\" class=\"acod-body collapse show\" data-parent=\"#accordionF48C2254\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u062a\u0627\u0631\u064a\u062e \u0627\u0644\u0646\u0638\u0631\u064a\u0627\u062a \u0648\u0627\u0644\u0623\u0641\u0643\u0627\u0631 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0629 \u0645\u0646 \u0639\u0635\u0631 \u0627\u0644\u064a\u0648\u0646\u0627\u0646 \u0625\u0644\u064a \u0627\u0644\u0642\u0631\u0646 \u0627\u0644\u0639\u0634\u0631\u064a\u0646<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22282\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u0645\u062e\u0631\u062c\u0627\u062a \u0627\u0644\u062a\u0639\u0644\u064a\u0645\u064a\u0629 (ILOs)\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22282\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2254\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0627\u0644\u0642\u062f\u0631\u0629 \u0639\u0644\u064a \u0641\u0647\u0645 \u0627\u0644\u0622\u0631\u0627\u0621 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0629 \u0648\u0641\u0642 \u0645\u0642\u062a\u0636\u064a\u0627\u062a \u0627\u0644\u0639\u0635\u0631 \u0627\u0644\u0630\u064a \u0638\u0647\u0631\u062a \u0641\u064a\u0647\u060c \u0645\u0646 \u062e\u0644\u0627\u0644 \u062a\u0642\u062f\u064a\u0645 \u0645\u0627\u062f\u0629 \u062a\u0627\u0631\u064a\u062e \u0627\u0644\u0641\u0643\u0631 \u0641\u064a \u0633\u064a\u0627\u0642\u0647\u0627 \u0627\u0644\u062a\u0627\u0631\u064a\u062e\u064a \u0648\u0627\u0644\u062a\u0639\u0631\u064a\u0641 \u0628\u062a\u0627\u0631\u064a\u062e \u0627\u0644\u0641\u0643\u0631 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u060c \u0625\u0628\u0631\u0627\u0632 \u0623\u0647\u0645\u064a\u0629 \u062a\u0627\u0631\u064a\u062e \u0627\u0644\u0641\u0643\u0631 \u0648\u0623\u0647\u0645\u064a\u0629 \u062f\u0631\u0627\u0633\u062a\u0647 \u0645\u0646 \u0628\u064a\u0646 \u0627\u0644\u0645\u0646\u0627\u0647\u062c \u0627\u0644\u0645\u0633\u062a\u0647\u062f\u0641 \u062a\u062f\u0631\u064a\u0633\u0647\u0627\u060c \u062a\u0642\u062f\u064a\u0645 \u0645\u0627\u062f\u0629 \u062a\u0627\u0631\u064a\u062e \u0627\u0644\u0641\u0643\u0631 \u0641\u064a \u0633\u064a\u0627\u0642\u0647\u0627 \u0627\u0644\u062a\u0627\u0631\u064a\u062e\u064a \u0648\u0627\u0644\u062a\u0639\u0631\u064a\u0641 \u0628\u062a\u0627\u0631\u064a\u062e \u0627\u0644\u0641\u0643\u0631 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22382\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0637\u0631\u064a\u0642\u0629\u0627\u0644\u062a\u062f\u0631\u064a\u0633 Teaching Strategy\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22382\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2254\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>1.\u0627\u0644\u0645\u062d\u0627\u0636\u0631\u0627\u062a \u0627\u0644\u062f\u0631\u0627\u0633\u064a\u0629 .<\/p>\n<p>2.\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 .<\/p>\n<p>3.\u0627\u0639\u062f\u0627\u062f \u0627\u0648\u0631\u0627\u0642 \u0628\u062d\u062b\u064a\u0629 \u0648\u0645\u0646\u0627\u0642\u0634\u062a\u0647\u0627 .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22482\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u062a\u0642\u064a\u064a\u0645 Assessment\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22482\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2254\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u062a\u062a\u0645 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0639\u0645\u0644 \u0627\u0645\u062a\u062d\u0627\u0646 \u062a\u062d\u0631\u064a\u0631\u064a \u0646\u0635\u0641\u0649\u060c \u0648\u0634\u0641\u0648\u064a\u060c \u0648\u0648\u0627\u062c\u0628 \u062f\u0631\u0627\u0633\u064a\u060c \u0648\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 \u0648\u0627\u0645\u062a\u062d\u0627\u0646 \u0646\u0647\u0627\u0626\u0649.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-12 m-b30\">\r\n\t\t\t\t\t\t\t<h2 class=\"m-b10 m-t0\">\r\n\t\t\t\t\t\t\t\t\u062a\u062d\u0644\u064a\u0644 \u0648\u062a\u0642\u064a\u064a\u0645 \u0627\u0644\u0627\u0648\u0631\u0627\u0642 \u0627\u0644\u0645\u0627\u0644\u064a\u0629\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<div class=\"dez-accordion space\" id=\"accordionF48C2255\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22187\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0646\u0638\u0631\u0629 \u0639\u0627\u0645\u0629 \u0639\u0646 \u0627\u0644\u0645\u0642\u0631\u0631 Overview\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22187\" class=\"acod-body collapse show\" data-parent=\"#accordionF48C2255\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0645\u0642\u0631\u0631 \u062a\u062d\u0644\u064a\u0644 \u0648\u062a\u0642\u064a\u064a\u0645 \u0627\u0644\u0627\u0648\u0631\u0627\u0642 \u0627\u0644\u0645\u0627\u0644\u064a\u0629 \u0630\u0627 \u0627\u0647\u0645\u064a\u0629 \u0644\u0644\u0637\u0627\u0644\u0628 \u062d\u064a\u062b \u064a\u0632\u0648\u062f\u0647 \u0628\u0627\u0644\u0645\u0641\u0627\u0647\u064a\u0645 \u0627\u0644\u0636\u0631\u0648\u0631\u064a\u0629 \u0627\u0644\u0645\u062a\u0639\u0644\u0642\u0629 \u0628\u0627\u0627\u0647\u0645 \u0627\u0644\u0627\u0648\u0631\u0627\u0642 \u0627\u0644\u0645\u0627\u0644\u064a\u0629 \u0648\u064a\u0632\u0648\u062f\u0647 \u0627\u064a\u0636\u0627 \u0628\u0643\u064a\u0641\u064a\u0629 \u062a\u0642\u064a\u064a\u0645 \u0648\u062a\u062d\u0644\u064a\u0644 \u0627\u0644\u0627\u0648\u0631\u0627\u0642 \u0627\u0644\u0645\u0627\u0644\u064a\u0629 \u0648\u0645\u0639\u0631\u0641\u0629 \u0648\u0638\u0627\u0626\u0641\u0647\u0627 \u0648\u0645\u0632\u0627\u064a\u0627\u0647\u0627 \u0648\u064a\u0634\u0631\u062d \u0644\u0647 \u0643\u064a\u0641\u064a\u0629 \u062d\u0633\u0627\u0628 \u0645\u062e\u0627\u0637\u0631 \u0648\u0637\u0631\u0642 \u0627\u0644\u062a\u0639\u0627\u0645\u0644 \u0628\u0627\u0644\u0627\u0648\u0631\u0627\u0642 \u0627\u0644\u0645\u0627\u0644\u064a\u0629 \u0628\u064a\u0639\u0627 \u0648\u0634\u0631\u0627\u0621\u0627 .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22287\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u0645\u062e\u0631\u062c\u0627\u062a \u0627\u0644\u062a\u0639\u0644\u064a\u0645\u064a\u0629 (ILOs)\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22287\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2255\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u064a\u0645\u0643\u0646\u0647\u0645 \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0631\u0631 \u0645\u0646 \u0645\u0639\u0631\u0641\u0647 \u0627\u0644\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u064a \u064a\u0633\u062a\u0637\u064a\u0639\u0648\u0646 \u0628\u0647\u0627 \u062a\u0642\u064a\u064a\u0645 \u0627\u0644\u0627\u0648\u0631\u0627\u0642 \u0627\u0644\u0645\u0627\u0644\u064a\u0629 \u0648\u0627\u0644\u0627\u0633\u062a\u062b\u0645\u0627\u0631 \u0641\u064a\u0647 \u0628\u064a\u0639\u0627 \u0648\u0634\u0631\u0627\u0621 , \u0645\u0645\u0627 \u064a\u0645\u0643\u0646\u0647\u0645 \u0645\u0646 \u062a\u062d\u062f\u064a\u062f \u0645\u0641\u0647\u0648\u0645 \u0627\u0644\u062e\u0637\u0631 \u0627\u0644\u0630\u064a \u062a\u062a\u0639\u0631\u0636 \u0644\u0647 \u0627\u0644\u0627\u0648\u0631\u0627\u0642 \u0627\u0644\u0645\u0627\u0644\u064a\u0629 \u0648\u0627\u0633\u0627\u0644\u064a\u0628 \u0648\u0637\u0631\u0642 \u0642\u064a\u0627\u0633\u0647\u0627 .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22387\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u062f\u0631\u064a\u0633 Teaching Strategy\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22387\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2255\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<ol>\n<li>\u0627\u0644\u0645\u062d\u0627\u0636\u0631\u0627\u062a .<\/li>\n<li>\u0627\u0644\u0627\u0648\u0631\u0627\u0642 \u0627\u0644\u0628\u062d\u062b\u064a\u0629 .<\/li>\n<li>\u00a0\u0627\u0644\u0648\u0627\u062c\u0628\u0627\u062a \u0627\u0644\u0645\u0646\u0632\u0644\u064a\u0629.<\/li>\n<li style=\"text-align: right;\">\u0627\u0644\u062a\u0639\u0644\u0645 \u0627\u0644\u0630\u0627\u062a\u064a .<\/li>\n<\/ol>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22487\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u062a\u0642\u064a\u064a\u0645 Assessment\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22487\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2255\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u062a\u062a\u0645 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0639\u0645\u0644 \u0627\u0645\u062a\u062d\u0627\u0646 \u062a\u062d\u0631\u064a\u0631\u064a\u060c \u0648\u0634\u0641\u0648\u064a\u060c \u0648\u0648\u0627\u062c\u0628 \u062f\u0631\u0627\u0633\u064a\u060c \u0639\u0631\u0636 \u0644\u0648\u0631\u0642\u0629 \u0628\u062d\u062b\u064a\u0629 .<\/p>\n<p>&nbsp;<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-12 m-b30\">\r\n\t\t\t\t\t\t\t<h2 class=\"m-b10 m-t0\">\r\n\t\t\t\t\t\t\t\t\u0645\u0627\u0644\u064a\u0629 \u0627\u0644\u0634\u0631\u0643\u0627\u062a\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<div class=\"dez-accordion space\" id=\"accordionF48C2265\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22189\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0646\u0638\u0631\u0629\u0639\u0627\u0645\u0629\u0639\u0646 \u0627\u0644\u0645\u0642\u0631\u0631 Overview\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22189\" class=\"acod-body collapse show\" data-parent=\"#accordionF48C2265\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u064a\u062a\u0636\u0645\u0646 \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0631\u0631 \u0639\u062f\u062f \u0645\u0646 \u0627\u0644\u0645\u0648\u0636\u0648\u0639\u0627\u062a \u0627\u0644\u062a\u064a \u062a\u062a\u0646\u0627\u0648\u0644 \u0627\u0644\u0625\u0637\u0627\u0631 \u0627\u0644\u0639\u0627\u0645 \u0644\u062f\u0631\u0627\u0633\u0629 \u0642\u0631\u0627\u0631 \u0627\u0644\u062a\u0645\u0648\u064a\u0644\u060c \u062a\u0645\u0648\u064a\u0644 \u0631\u0623\u0633 \u0627\u0644\u0645\u0627\u0644 \u0627\u0644\u0639\u0627\u0645\u0644\u060c \u0645\u0635\u0627\u062f\u0631 \u0627\u0644\u062a\u0645\u0648\u064a\u0644\u060c \u062a\u0642\u062f\u064a\u0631 \u062a\u0643\u0644\u0641\u0629 \u0645\u0635\u0627\u062f\u0631 \u0627\u0644\u0623\u0645\u0648\u0627\u0644\u060c \u062a\u0642\u062f\u064a\u0631 \u0627\u0644\u0645\u062a\u0648\u0633\u0637 \u0627\u0644\u0645\u0631\u062c\u062d \u0644\u062a\u0643\u0644\u0641\u0629 \u0627\u0644\u062a\u0645\u0648\u064a\u0644\u060c \u0627\u0644\u0627\u0639\u062a\u0628\u0627\u0631\u0627\u062a \u0627\u0644\u062d\u0627\u0643\u0645\u0629 \u0644\u062a\u062f\u0628\u064a\u0631 \u0627\u0644\u0623\u0645\u0648\u0627\u0644\u060c \u0627\u0644\u0645\u0641\u0627\u0636\u0644\u0629 \u0628\u064a\u0646 \u0627\u0644\u0628\u062f\u0627\u0626\u0644 \u0627\u0644\u062a\u0645\u0648\u064a\u0644\u064a\u0629\u060c \u0642\u064a\u0627\u0633 \u0627\u0644\u0642\u062f\u0631\u0629 \u0627\u0644\u0625\u0642\u062a\u0631\u0627\u0636\u064a\u0629 \u0644\u0644\u0634\u0631\u0643\u0629\u060c \u0646\u0638\u0631\u064a\u0627\u062a \u0647\u064a\u0643\u0644 \u0627\u0644\u062a\u0645\u0648\u064a\u0644 \u0627\u0644\u0623\u0645\u062b\u0644\u060c \u0642\u0631\u0627\u0631 \u0627\u0644\u062a\u0648\u0632\u064a\u0639.<\/p>\n<p>&nbsp;<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22289\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u0645\u062e\u0631\u062c\u0627\u062a \u0627\u0644\u062a\u0639\u0644\u064a\u0645\u064a\u0629 (ILOs)\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22289\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2265\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0628\u0646\u0647\u0627\u064a\u0629 \u0627\u0644\u0645\u0642\u0631\u0631 \u0633\u064a\u0643\u0648\u0646 \u0627\u0644\u0637\u0627\u0644\u0628 \u0642\u0627\u062f\u0631\u0627 \u0639\u0644\u0649 \u0623\u0646:<\/p>\n<ul>\n<li>\u064a\u0634\u0631\u062d \u0627\u0644\u0645\u0641\u0627\u0647\u064a\u0645 \u0627\u0644\u0623\u0633\u0627\u0633\u064a\u0629 \u0641\u064a \u062a\u0645\u0648\u064a\u0644 \u0627\u0644\u0634\u0631\u0643\u0627\u062a.<\/li>\n<li>\u064a\u0631\u0628\u0637 \u0628\u064a\u0646 \u0627\u0644\u0645\u0641\u0627\u0647\u064a\u0645 \u0627\u0644\u0623\u0633\u0627\u0633\u064a\u0629 \u0648\u0627\u0644\u0645\u0645\u0627\u0631\u0633\u0627\u062a \u0627\u0644\u062a\u0637\u0628\u064a\u0642\u064a\u0629 \u0641\u064a \u0645\u062c\u0627\u0644 \u062a\u0645\u0648\u064a\u0644 \u0627\u0644\u0634\u0631\u0643\u0627\u062a.<\/li>\n<li>\u064a\u062d\u0644\u0644 \u0638\u0648\u0627\u0647\u0631 \u0648\u0645\u0634\u0643\u0644\u0627\u062a \u0641\u064a \u0645\u062c\u0627\u0644 \u062a\u0645\u0648\u064a\u0644 \u0627\u0644\u0634\u0631\u0643\u0627\u062a.<\/li>\n<li>\u064a\u0635\u0645\u0645 \u0625\u0637\u0627\u0631\u0627\u064b \u0644\u0639\u0644\u0627\u062c \u0645\u0634\u0643\u0644\u0627\u062a \u062a\u062d\u062f\u062b \u0641\u064a \u0645\u062c\u0627\u0644 \u062a\u0645\u0648\u064a\u0644 \u0627\u0644\u0634\u0631\u0643\u0627\u062a<\/li>\n<li>\u064a\u0645\u0627\u0631\u0633 \u0642\u064a\u0645 \u0627\u0644\u0639\u0645\u0644 \u0627\u0644\u062c\u0645\u0627\u0639\u064a \u0645\u0646 \u062e\u0644\u0627\u0644 \u062a\u0635\u0645\u064a\u0645 \u062e\u0637\u0629 \u0644\u062a\u0646\u0641\u064a\u0630 \u0645\u0634\u0631\u0648\u0639 \u0628\u062d\u062b\u064a \u0641\u064a \u062a\u0645\u0648\u064a\u0644 \u0627\u0644\u0634\u0631\u0643\u0627\u062a \u0628\u0627\u0644\u062a\u0639\u0627\u0648\u0646 \u0645\u0639 \u0632\u0645\u0644\u0627\u0621\u0647.<\/li>\n<li>\u064a\u0637\u0628\u0642 \u0623\u0635\u0648\u0644 \u0627\u0644\u0628\u062d\u062b \u0627\u0644\u0639\u0644\u0645\u064a \u0641\u064a \u062a\u0646\u0641\u064a\u0630 \u0627\u0644\u0645\u0634\u0631\u0648\u0639 \u0627\u0644\u0628\u062d\u062b\u064a \u0641\u064a \u0645\u062c\u0627\u0644 \u062a\u0645\u0648\u064a\u0644 \u0627\u0644\u0634\u0631\u0643\u0627\u062a.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22389\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0637\u0631\u064a\u0642\u0629\u0627\u0644\u062a\u062f\u0631\u064a\u0633 Teaching Strategy\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22389\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2265\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>1.\u0627\u0644\u0645\u062d\u0627\u0636\u0631\u0627\u062a \u0627\u0644\u062f\u0631\u0627\u0633\u064a\u0629 .<\/p>\n<p>2.\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 .<\/p>\n<p>3.\u0627\u0639\u062f\u0627\u062f \u0627\u0648\u0631\u0627\u0642 \u0628\u062d\u062b\u064a\u0629 \u0648\u0645\u0646\u0627\u0642\u0634\u062a\u0647\u0627 .<\/p>\n<p>&nbsp;<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22489\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u062a\u0642\u064a\u064a\u0645 Assessment\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22489\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2265\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u062a\u062a\u0645 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0639\u0645\u0644 \u0627\u0645\u062a\u062d\u0627\u0646 \u062a\u062d\u0631\u064a\u0631\u064a \u0646\u0635\u0641\u0649\u060c \u0648\u0634\u0641\u0648\u064a\u060c \u0648\u0648\u0627\u062c\u0628 \u062f\u0631\u0627\u0633\u064a\u060c \u0648\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 \u0648\u0627\u0645\u062a\u062d\u0627\u0646 \u0646\u0647\u0627\u0626\u0649. .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-12 m-b30\">\r\n\t\t\t\t\t\t\t<h2 class=\"m-b10 m-t0\">\r\n\t\t\t\t\t\t\t\t\u0645\u0628\u0627\u062f\u0626 \u0627\u0644\u062a\u0633\u0648\u064a\u0642\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<div class=\"dez-accordion space\" id=\"accordionF48C2269\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22181\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0646\u0638\u0631\u0629\u0639\u0627\u0645\u0629\u0639\u0646 \u0627\u0644\u0645\u0642\u0631\u0631 Overview\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22181\" class=\"acod-body collapse show\" data-parent=\"#accordionF48C2269\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u064a\u062f\u0631\u0633 \u0627\u0644\u0637\u0644\u0627\u0628 \u0641\u064a \u0647\u062f\u0627 \u0627\u0644\u0645\u0642\u0631\u0631 \u0639\u0645\u0644\u064a\u0629\u0627\u0644\u062a\u0633\u0648\u064a\u0642\u0648\u0637\u0628\u064a\u0639\u062a\u0647\u060c \u0627\u0644\u062a\u0633\u0648\u064a\u0642\u0641\u064a\u0627\u0644\u0639\u0635\u0631\u0627\u0644\u0631\u0642\u0645\u064a\u060c \u062a\u062d\u0644\u064a\u0644\u0627\u0644\u0628\u064a\u0626\u0629\u0627\u0644\u062a\u0633\u0648\u064a\u0642\u064a\u0629\u060c \u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u062a\u0633\u0648\u064a\u0642\u060c\u062a\u062e\u0637\u064a\u0637\u0627\u0644\u062a\u0633\u0648\u064a\u0642\u060c\u0628\u062d\u0648\u062b\u0627\u0644\u062a\u0633\u0648\u064a\u0642\u060c \u0646\u0638\u0645\u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a\u0627\u0644\u062a\u0633\u0648\u064a\u0642\u064a\u0629\u060c \u0627\u0644\u0645\u0632\u064a\u062c\u0627\u0644\u062a\u0633\u0648\u064a\u0642\u064a\u060c \u0627\u0633\u062a\u0631\u0627\u062a\u064a\u062c\u064a\u0627\u062a\u0627\u0644\u062a\u0633\u0639\u064a\u0631\u0648\u0627\u0644\u062a\u0648\u0632\u064a\u0639\u060c \u0627\u0644\u0628\u064a\u0639\u0627\u0644\u0634\u062e\u0635\u064a\u0648\u063a\u064a\u0631\u0627\u0644\u0634\u062e\u0635\u064a.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22281\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u0645\u062e\u0631\u062c\u0627\u062a \u0627\u0644\u062a\u0639\u0644\u064a\u0645\u064a\u0629 (ILOs)\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22281\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2269\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0639\u0646\u062f \u0627\u0644\u0627\u0646\u062a\u0647\u0627\u0621 \u0645\u0646 \u0647\u062f\u0627 \u0627\u0644\u0645\u0642\u0631\u0631 \u0633\u064a\u0643\u0648\u0646 \u0627\u0644\u0637\u0627\u0644\u0628 \u0642\u0627\u062f\u0631\u0627\u064b \u0639\u0644\u0649:<\/p>\n<ul>\n<li>\u064a\u0647\u062f\u0641 \u0627\u0644\u0645\u0642\u0631\u0631 \u0627\u0644\u0649 \u0627\u0644\u062a\u0639\u0631\u064a\u0641 \u0628\u0645\u0641\u0647\u0648\u0645 \u0627\u0644\u062a\u0633\u0648\u064a\u0642 \u0648\u0627\u0644\u0628\u064a\u0626\u0629 \u0627\u0644\u062a\u0633\u0648\u064a\u0642\u064a\u0629.<\/li>\n<li>\u062a\u0648\u0636\u064a\u062d \u0645\u0641\u0647\u0648\u0645 \u0627\u0644\u0645\u0632\u064a\u062c \u0627\u0644\u062a\u0633\u0648\u064a\u0642\u064a.<\/li>\n<li>\u064a\u062a\u0639\u0631\u0641 \u0627\u0644\u0637\u0627\u0644\u0628 \u0639\u0644\u0649 \u0627\u0644\u064a\u0629 \u0627\u062c\u0631\u0627\u0621 \u0627\u0644\u0628\u062d\u0648\u062b \u0627\u0644\u062a\u0633\u0648\u064a\u0642\u064a\u0629 \u0648\u0645\u062c\u0627\u0644\u0627\u062a\u0647\u0627 \u0648\u0645\u0641\u0647\u0648\u0645 \u0627\u0644\u062a\u0633\u0648\u064a\u0642 \u0627\u0644\u062e\u062f\u0645\u064a \u0648\u0627\u0644\u0645\u0635\u0631\u0641\u064a \u0648\u0627\u0644\u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a<\/li>\n<\/ul>\n<p>\u0633\u064a\u0642\u062f\u0645 \u0627\u0644\u0645\u0642\u0631\u0631 \u0644\u0644\u0637\u0627\u0644\u0628:<\/p>\n<ul>\n<li>\u0645\u062d\u0627\u0636\u0631\u0627\u062a \u0645\u0646\u0647\u062c\u064a\u0629 \u0646\u0638\u0631\u064a\u0629 \u0648\u0639\u0645\u0644\u064a\u0629.<\/li>\n<li>\u0639\u0631\u0648\u0636 \u062a\u0642\u062f\u064a\u0645\u064a\u0629 \u0645\u062a\u0639\u0644\u0642\u0629 \u0628\u0627\u0644\u0645\u0642\u0631\u0631<\/li>\n<li>\u0627\u0644\u0646\u0634\u0627\u0637 \u0648\u0627\u0644\u0645\u0634\u0627\u0631\u0643\u0629 \u0648\u0627\u0644\u0648\u0627\u062c\u0628\u0627\u062a<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22381\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u062a\u0642\u064a\u064a\u0645 Assessment\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22381\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2269\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 (\u0627\u0645\u062a\u062d\u0627\u0646 \u0646\u0635\u0641\u064a\u060c \u0646\u0647\u0627\u0626\u064a \u060c\u0648\u0631\u0642\u0627\u062a \u0639\u0645\u0644) \u0639\u0644\u0649 \u0623\u0646 \u062a\u0643\u0648\u0646 \u0627\u0644\u062f\u0631\u062c\u0627\u062a \u0645\u0642\u0633\u0645\u0629 \u0639\u0644\u064a\u0647\u0646 \u0628\u062d\u0633\u0628 \u0645\u0627 \u064a\u0631\u0627\u0647 \u0627\u0644\u0623\u0633\u062a\u0627\u0630 \u0645\u0646\u0627\u0633\u0628 .<\/p>\n<p>&nbsp;<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-12 m-b30\">\r\n\t\t\t\t\t\t\t<h2 class=\"m-b10 m-t0\">\r\n\t\t\t\t\t\t\t\t\u0645\u0628\u0627\u062f\u0626 \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u0629 1\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<p>\r\n\t\t\t\t\t\t\t\t130\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<div class=\"dez-accordion space\" id=\"accordionF48C2270\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22192\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0646\u0638\u0631\u0629 \u0639\u0627\u0645\u0629 \u0639\u0646 \u0627\u0644\u0645\u0642\u0631\u0631 Overview\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22192\" class=\"acod-body collapse show\" data-parent=\"#accordionF48C2270\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u064a\u062a\u0646\u0627\u0648\u0644 \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0631\u0631 \u0637\u0628\u064a\u0639\u0629 \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u0629 \u0648\u062f\u0648\u0631\u0647\u0627 \u0641\u064a \u0627\u0644\u0645\u062c\u062a\u0645\u0639\u060c \u0648\u0627\u0644\u0645\u0641\u0627\u0647\u064a\u0645 \u0648\u0627\u0644\u0623\u0633\u0633 \u0627\u0644\u062a\u064a \u062a\u0642\u0648\u0645 \u0639\u0644\u064a\u0647\u0627\u060c \u0648\u062a\u0633\u062c\u064a\u0644 \u0627\u0644\u0623\u062d\u062f\u0627\u062b \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0629 \u0644\u0644\u0645\u0646\u0634\u0623\u0629 \u0648\u0627\u0644\u062a\u0639\u0631\u064a\u0641 \u0628\u0627\u0644\u062f\u0648\u0631\u0629 \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u064a\u0629 \u0648\u0625\u0639\u062f\u0627\u062f \u0627\u0644\u0642\u0648\u0627\u0626\u0645 \u0627\u0644\u0645\u0627\u0644\u064a\u0629\u060c \u0648\u0627\u0644\u0623\u0633\u0627\u0644\u064a\u0628 \u0648\u0627\u0644\u0637\u0631\u0642 \u0627\u0644\u062a\u064a \u062a\u0633\u062a\u062e\u062f\u0645\u0647\u0627 \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u0629 \u0641\u064a \u062a\u0648\u0641\u064a\u0631 \u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0639\u0646 \u0627\u0644\u0623\u062d\u062f\u0627\u062b \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0629.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22292\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u0645\u062e\u0631\u062c\u0627\u062a \u0627\u0644\u062a\u0639\u0644\u064a\u0645\u064a\u0629 (ILOs)\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22292\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2270\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0639\u0646\u062f \u0646\u0647\u0627\u064a\u0629 \u0627\u0644\u0645\u0642\u0631\u0631 \u064a\u0643\u0648\u0646 \u0627\u0644\u0637\u0627\u0644\u0628 \u0642\u0627\u062f\u0631\u0627 \u0639\u0644\u0649:<\/p>\n<p>\u064a\u0647\u062f\u0641 \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0631\u0631 \u0627\u0644\u0649 \u0625\u0643\u0633\u0627\u0628 \u0627\u0644\u0637\u0627\u0644\u0628 \u0628\u0627\u0644\u0642\u0648\u0627\u0639\u062f \u0648\u0627\u0644\u0645\u0628\u0627\u062f\u0626 \u0648\u0627\u0644\u0641\u0631\u0648\u0636 \u0648\u0627\u0644\u0633\u064a\u0627\u0633\u0627\u062a \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u064a\u0629 \u0648\u0645\u0647\u0627\u0631\u0627\u062a \u062a\u0633\u062c\u064a\u0644 \u0627\u0644\u0639\u0645\u0644\u064a\u0627\u062a \u0627\u0644\u0645\u0627\u0644\u064a\u0629 \u0641\u064a \u0627\u0644\u062f\u0641\u0627\u062a\u0631 \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u064a\u0629 \u0648\u0625\u0639\u062f\u0627\u062f \u0627\u0644\u0642\u0648\u0627\u0626\u0645 \u0627\u0644\u0645\u0627\u0644\u064a\u0629 \u0627\u0644\u062e\u062a\u0627\u0645\u064a\u0629 \u0644\u0625\u0638\u0647\u0627\u0631 \u0646\u062a\u064a\u062c\u0629 \u0623\u0639\u0645\u0627\u0644 \u0627\u0644\u0645\u0646\u0634\u0623\u0629 \u0648\u0643\u0630\u0644\u0643 \u0627\u0644\u0645\u0631\u0643\u0632 \u0627\u0644\u0645\u0627\u0644\u064a \u0644\u0644\u0645\u0646\u0634\u0623\u0629 \u0648\u0641\u0642\u0627 \u0644\u0644\u0645\u0639\u0627\u064a\u064a\u0631 \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u064a\u0629 \u060c \u0648\u062a\u0648\u0641\u064a\u0631 \u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0645\u0627\u0644\u064a\u0629 \u0645\u0641\u064a\u062f\u0629 \u0644\u0644\u0645\u0633\u062a\u0641\u064a\u062f\u064a\u0646 \u0645\u0646 \u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u064a\u0629. \u0648\u064a\u0634\u062a\u0645\u0644 \u0627\u0644\u0645\u0642\u0631\u0631 \u0639\u0644\u0649 \u0623\u0633\u0627\u0633\u064a\u0627\u062a \u0627\u0644\u0642\u064a\u062f \u0627\u0644\u0645\u0632\u062f\u0648\u062c \u0641\u064a \u062a\u062d\u0644\u064a\u0644 \u0648\u062a\u0633\u062c\u064a\u0644 \u0627\u0644\u0645\u0639\u0627\u0645\u0644\u0627\u062a \u0627\u0644\u0645\u0627\u0644\u064a\u0629 \u0648 \u0627\u0633\u062a\u062e\u0631\u0627\u062c \u0645\u064a\u0632\u0627\u0646 \u0627\u0644\u0645\u0631\u0627\u062c\u0639\u0629. \u0647\u0630\u0627 \u0641\u0636\u0644\u0627\u064b \u0639\u0644\u0649 \u0625\u0639\u062f\u0627\u062f \u0627\u0644\u0642\u0648\u0627\u0626\u0645 \u0627\u0644\u0645\u0627\u0644\u064a\u0629 \u0644\u062a\u062d\u062f\u064a\u062f \u0646\u062a\u064a\u062c\u0629 \u0627\u0644\u0623\u0639\u0645\u0627\u0644 \u0648\u0627\u0644\u0645\u0631\u0643\u0632 \u0627\u0644\u0645\u0627\u0644\u064a \u0644\u0644\u0645\u0646\u0634\u0623\u0629 \u0641\u064a \u0646\u0647\u0627\u064a\u0629 \u0627\u0644\u0641\u062a\u0631\u0629 \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u064a\u0629 \u0648\u062a\u0635\u062d\u064a\u062d \u0627\u0644\u0623\u062e\u0637\u0627\u0621.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22392\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0637\u0631\u064a\u0642\u0629\u0627\u0644\u062a\u062f\u0631\u064a\u0633 Teaching Strategy\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22392\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2270\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>&nbsp;<\/p>\n<p>1. \u0627\u0644\u0645\u062d\u0627\u0636\u0631\u0627\u062a \u0627\u0644\u062f\u0631\u0627\u0633\u064a\u0629 .<\/p>\n<p>2 .\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 .<\/p>\n<p>3. \u0627\u0639\u062f\u0627\u062f \u0627\u0648\u0631\u0627\u0642 \u0628\u062d\u062b\u064a\u0629 \u0648\u0645\u0646\u0627\u0642\u0634\u062a\u0647\u0627 .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22492\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u062a\u0642\u064a\u064a\u0645 Assessment\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22492\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2270\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u062a\u062a\u0645 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0639\u0645\u0644 \u0627\u0645\u062a\u062d\u0627\u0646 \u062a\u062d\u0631\u064a\u0631\u064a \u0646\u0635\u0641\u0649\u060c \u0648\u0634\u0641\u0648\u064a\u060c \u0648\u0648\u0627\u062c\u0628 \u062f\u0631\u0627\u0633\u064a\u060c \u0648\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 \u0648\u0627\u0645\u062a\u062d\u0627\u0646 \u0646\u0647\u0627\u0626\u0649. .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-12 m-b30\">\r\n\t\t\t\t\t\t\t<h2 class=\"m-b10 m-t0\">\r\n\t\t\t\t\t\t\t\t\u0645\u0628\u0627\u062f\u0626 \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u0629 2\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<p>\r\n\t\t\t\t\t\t\t\t131\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<div class=\"dez-accordion space\" id=\"accordionF48C2271\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22175\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0646\u0638\u0631\u0629\u0639\u0627\u0645\u0629\u0639\u0646\u0627\u0644\u0645\u0642\u0631\u0631 Overview\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22175\" class=\"acod-body collapse show\" data-parent=\"#accordionF48C2271\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u064a\u0647\u062f\u0641 \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0631\u0631 \u0625\u0644\u0649 \u0627\u0633\u062a\u0643\u0645\u0627\u0644 \u062f\u0631\u0627\u0633\u0629 \u0627\u0644\u0645\u0628\u0627\u062f\u0626 \u0648\u0627\u0644\u0625\u062c\u0631\u0627\u0621\u0627\u062a \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u064a\u0629 \u0627\u0644\u062a\u064a \u062a\u0645 \u062a\u0646\u0627\u0648\u0644\u0647\u0627 \u0641\u064a \u0645\u0642\u0631\u0631 \u0645\u0628\u0627\u062f\u0626 \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u0629 (130) \u0648\u064a\u0631\u0643\u0632 \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0631\u0631 \u0639\u0644\u0649 \u0627\u0644\u062a\u0633\u0648\u064a\u0627\u062a \u0627\u0644\u062c\u0631\u062f\u064a\u0629 \u0644\u0645\u062e\u062a\u0644\u0641 \u0627\u0644\u062d\u0633\u0627\u0628\u0627\u062a \u0648\u0625\u0639\u062f\u0627\u062f \u0627\u0644\u0642\u0648\u0627\u0626\u0645 \u0627\u0644\u0645\u0627\u0644\u064a\u0629 \u0628\u0639\u062f \u0627\u0644\u062a\u0633\u0648\u064a\u0627\u062a \u0627\u0644\u062c\u0631\u062f\u064a\u0629 \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u062f\u0641\u0627\u062a\u0631 \u0627\u0644\u0645\u0633\u0627\u0639\u062f\u0629 \u0648\u0627\u0644\u0637\u0631\u0642 \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u064a\u0629<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22275\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u0645\u062e\u0631\u062c\u0627\u062a\u0627\u0644\u062a\u0639\u0644\u064a\u0645\u064a\u0629Intended Learning Outcomes (ILOs)\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22275\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2271\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0639\u0646\u062f \u0646\u0647\u0627\u064a\u0629 \u0627\u0644\u0645\u0642\u0631\u0631 \u064a\u0643\u0648\u0646 \u0627\u0644\u0637\u0627\u0644\u0628 \u0642\u0627\u062f\u0631\u0627 \u0639\u0644\u0649:<\/p>\n<p>\u0644\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0627\u0644\u062d\u0635\u0631 \u0627\u0644\u0641\u0639\u0644\u064a \u0644\u062c\u0645\u064a\u0639 \u0628\u0646\u0648\u062f \u0627\u0644\u0625\u064a\u0631\u0627\u062f\u0627\u062a \u0648\u0627\u0644\u0645\u0635\u0631\u0648\u0641\u0627\u062a \u0648\u0627\u0644\u0623\u0635\u0648\u0644 \u0648\u0627\u0644\u062e\u0635\u0648\u0645 \u0627\u0644\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0643\u064a\u0641\u064a\u0629 \u0625\u0639\u062f\u0627\u062f \u0627\u0644\u062d\u0633\u0627\u0628\u0627\u062a \u0627\u0644\u062e\u062a\u0627\u0645\u064a\u0629 \u0628\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0648\u0631\u0642\u0629 \u0627\u0644\u062a\u0633\u0648\u064a\u0629 \u062a\u0639\u0644\u064a\u0645 \u0627\u0644\u0637\u0627\u0644\u0628 \u0643\u064a\u0641\u064a\u0629 \u0627\u062c\u0631\u0627\u0621 \u0627\u0644\u062a\u0633\u0648\u064a\u0627\u062a \u0627\u0644\u062c\u0631\u062f\u064a\u0629 \u0644\u0644\u0623\u0635\u0648\u0644 \u0648\u0627\u0644\u062e\u0635\u0648\u0645 \u0648\u0627\u0644\u0625\u064a\u0631\u0627\u062f\u0627\u062a \u0648\u0627\u0644\u0645\u0635\u0631\u0648\u0641\u0627\u062a \u0641\u064a \u0646\u0647\u0627\u064a\u0629 \u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0645\u0627\u0644\u064a\u0629 \u062a\u0639\u0644\u064a\u0645 \u0627\u0644\u0637\u0627\u0644\u0628 \u0643\u064a\u0641\u064a\u0629 \u0627\u0639\u062f\u0627\u062f \u0627\u0644\u0642\u0648\u0627\u0626\u0645 \u0627\u0644\u0645\u0627\u0644\u064a\u0629 \u0628\u0639\u062f \u0627\u0644\u062a\u0633\u0648\u064a\u0627\u062a \u0644\u0644\u062d\u0635\u0648\u0644 \u0639\u0644\u064a \u0628\u064a\u0627\u0646\u0627\u062a \u0627\u0644\u0641\u0639\u0644\u064a\u0629 \u0644\u0644\u0642\u0648\u0627\u0626\u0645 \u0627\u0644\u0645\u0627\u0644\u064a\u0629<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22375\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0637\u0631\u064a\u0642\u0629\u0627\u0644\u062a\u062f\u0631\u064a\u0633 Teaching Strategy\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22375\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2271\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>1.\u0627\u0644\u0645\u062d\u0627\u0636\u0631\u0627\u062a \u0627\u0644\u062f\u0631\u0627\u0633\u064a\u0629 .<\/p>\n<p>2.\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 .<\/p>\n<p>3.\u0627\u0639\u062f\u0627\u062f \u0627\u0648\u0631\u0627\u0642 \u0628\u062d\u062b\u064a\u0629 \u0648\u0645\u0646\u0627\u0642\u0634\u062a\u0647\u0627 .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22475\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u062a\u0642\u064a\u064a\u0645 Assessment\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22475\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2271\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u062a\u062a\u0645 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0639\u0645\u0644 \u0627\u0645\u062a\u062d\u0627\u0646 \u062a\u062d\u0631\u064a\u0631\u064a \u0646\u0635\u0641\u0649\u060c \u0648\u0634\u0641\u0648\u064a\u060c \u0648\u0648\u0627\u062c\u0628 \u062f\u0631\u0627\u0633\u064a\u060c \u0648\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 \u0648\u0627\u0645\u062a\u062d\u0627\u0646 \u0646\u0647\u0627\u0626\u0649<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-12 m-b30\">\r\n\t\t\t\t\t\t\t<h2 class=\"m-b10 m-t0\">\r\n\t\t\t\t\t\t\t\t\u0645\u0628\u0627\u062f\u064a \u0627\u0644\u062a\u0645\u0648\u064a\u0644 1\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<p>\r\n\t\t\t\t\t\t\t\t112\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<div class=\"dez-accordion space\" id=\"accordionF48C2273\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22173\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0646\u0638\u0631\u0629 \u0639\u0627\u0645\u0629 \u0639\u0646 \u0627\u0644\u0645\u0642\u0631\u0631 Overview\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22173\" class=\"acod-body collapse show\" data-parent=\"#accordionF48C2273\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u064a\u0647\u062a\u0645 \u0628\u062a\u0639\u0631\u064a\u0641 \u0627\u0644\u0637\u0627\u0644\u0628 \u0628\u0627\u0644\u062a\u0645\u0648\u064a\u0644 \u0648\u0645\u0627\u0647\u064a \u0648\u0638\u064a\u0641\u0629 \u0627\u0644\u062a\u0645\u0648\u064a\u0644 \u0641\u064a \u0627\u0644\u0645\u0646\u0634\u0627\u0629 , \u0648\u0645\u0627\u0647\u064a \u0627\u0644\u0645\u0647\u0627\u0645 \u0627\u0644\u0645\u0648\u0643\u0644\u0629 \u0627\u0644\u064a \u0627\u0644\u0645\u062f\u064a\u0631\u064a\u0646 \u0627\u0644\u0645\u0627\u0644\u064a\u064a\u0646 , \u0648\u064a\u0639\u0631\u0641 \u0627\u0644\u0637\u0627\u0644\u0628 \u0628\u062f\u0648\u0631 \u0627\u0644\u062a\u0645\u0648\u064a\u0644 \u0641\u064a \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f \u0627\u0644\u0642\u0648\u0645\u064a \u0648\u0645\u0635\u0627\u062f\u0631 \u0627\u0644\u062a\u0645\u0648\u064a\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 , \u0648\u0645\u0639\u0646\u064a \u0627\u0644\u0627\u0633\u062a\u062b\u0645\u0627\u0631 \u0648\u0627\u0646\u0648\u0627\u0639\u0647 \u0648\u0627\u062f\u0648\u0627\u062a \u0627\u0644\u0627\u0633\u062a\u062b\u0645\u0627\u0631 \u0648\u0627\u064a\u0636\u0627 \u0627\u0644\u062a\u0639\u0631\u064a\u0641 \u0628\u0627\u0644\u0645\u0641\u0627\u0647\u064a\u0645 \u0627\u0644\u0639\u0627\u0645\u0629 \u0644\u0644\u0627\u0633\u0648\u0627\u0642 \u0627\u0644\u0645\u0627\u0644\u064a\u0629 \u0648\u0627\u0646\u0648\u0627\u0639\u0647\u0627 .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22273\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u0645\u062e\u0631\u062c\u0627\u062a \u0627\u0644\u062a\u0639\u0644\u064a\u0645\u064a\u0629\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22273\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2273\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u064a\u0645\u0643\u0646\u0647\u0645 \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0631\u0631 \u0645\u0646 \u0645\u0639\u0631\u0641\u0647 \u0627\u0644\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u064a \u064a\u0633\u062a\u0637\u064a\u0639\u0648\u0646 \u0628\u0647\u0627 \u062f\u0631\u0627\u0633\u0629 \u0648\u0645\u0639\u0631\u0641\u0647 \u0648\u0638\u064a\u0641\u0629 \u0627\u0644\u062a\u0645\u0648\u064a\u0644 \u0648\u0637\u0631\u0642 \u0627\u0644\u062a\u0645\u0648\u064a\u0644 \u0648\u0643\u064a\u0641\u0629 \u0627\u0644\u0627\u062e\u062a\u064a\u0627\u0631 \u0641\u064a\u0645\u0627 \u0628\u064a\u0646\u0647\u0627 \u0648\u0627\u0644\u0645\u0646\u0627\u0633\u0628\u0629 \u0644\u0644\u062a\u0645\u0648\u064a\u0644 \u0644\u062a\u062c\u0646\u0628 \u0627\u0644\u062a\u0639\u0631\u0636 \u0627\u0644\u064a \u0645\u062e\u0627\u0637\u0631 \u0639\u062f\u0645 \u0627\u0644\u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u0627\u0645\u062b\u0644 \u0644\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u0645\u0648\u064a\u0644 \u0648\u064a\u0645\u0643\u0646\u0647\u0645 \u0627\u064a\u0636\u0627 \u0645\u0646 \u0645\u0639\u0631\u0641\u0629 \u0627\u0647\u0645\u064a\u0629 \u0627\u0644\u0642\u064a\u0645\u0629 \u0627\u0644\u0632\u0645\u0646\u064a\u0629 \u0644\u0644\u0646\u0642\u0648\u062f \u0641\u064a \u0627\u0644\u0627\u0633\u062a\u062b\u0645\u0627\u0631\u0627\u0644\u0645\u0627\u0644\u064a , \u0648\u0627\u0644\u062d\u062f \u0645\u0646 \u0645\u062e\u0627\u0637\u0631 \u0627\u0644\u0627\u0633\u062a\u062b\u0645\u0627\u0631 \u0627\u0644\u0645\u0627\u0644\u064a \u0642\u062f\u0631 \u0627\u0644\u0645\u0633\u062a\u0637\u0627\u0639 .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22373\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u062f\u0631\u064a\u0633\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22373\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2273\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>1.\u0627\u0644\u0645\u062d\u0627\u0636\u0631\u0627\u062a \u0627\u0644\u062f\u0631\u0627\u0633\u064a\u0629 .<\/p>\n<p>2.\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 .<\/p>\n<p>3.\u0627\u0639\u062f\u0627\u062f \u0627\u0648\u0631\u0627\u0642 \u0628\u062d\u062b\u064a\u0629 \u0648\u0645\u0646\u0627\u0642\u0634\u062a\u0647\u0627<\/p>\n<pre id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"\u0627\u0644\u062a\u0631\u062c\u0645\u0629\"><\/pre>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22473\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u062a\u0642\u064a\u064a\u0645\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22473\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2273\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u062a\u062a\u0645 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0639\u0645\u0644 \u0627\u0645\u062a\u062d\u0627\u0646 \u0646\u0635\u0641\u0649 \u062a\u062d\u0631\u064a\u0631\u064a\u060c \u0648\u0634\u0641\u0648\u064a\u060c \u0648\u0648\u0627\u062c\u0628 \u062f\u0631\u0627\u0633\u064a\u060c \u0648\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 \u0648\u0627\u0645\u062a\u062d\u0627\u0646 \u0646\u0647\u0627\u0626\u064a .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-12 m-b30\">\r\n\t\t\t\t\t\t\t<h2 class=\"m-b10 m-t0\">\r\n\t\t\t\t\t\t\t\t\u0645\u062d\u0627\u0633\u0628\u0629 \u0627\u0644\u0645\u0635\u0627\u0631\u0641\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<div class=\"dez-accordion space\" id=\"accordionF48C2280\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22191\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0646\u0638\u0631\u0629\u0639\u0627\u0645\u0629\u0639\u0646 \u0627\u0644\u0645\u0642\u0631\u0631 Overview\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22191\" class=\"acod-body collapse show\" data-parent=\"#accordionF48C2280\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u064a\u0634\u0645\u0644 \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0631\u0631 \u0639\u0644\u0649 \u0627\u0644\u062a\u0639\u0631\u064a\u0641 \u0628\u0627\u0644\u0645\u062d\u0627\u0633\u0628\u0629 \u0641\u064a \u0627\u0644\u0642\u0637\u0627\u0639 \u0627\u0644\u0645\u0635\u0631\u0641\u064a \u0648\u0642\u0637\u0627\u0639 \u0634\u0631\u0643\u0627\u062a \u0627\u0644\u062a\u0623\u0645\u064a\u0646 \u0628\u0634\u0643\u0644 \u0639\u0627\u0645\u060c \u0648\u0643\u0630\u0644\u0643 \u0627\u0644\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0627\u0644\u0645\u0646\u0638\u0648\u0645\u0627\u062a \u0648\u0627\u0644\u0645\u064a\u0643\u0646\u0629 \u0627\u0644\u0645\u0633\u062a\u062e\u062f\u0645\u0629 \u062f\u0627\u062e\u0644 \u0627\u0644\u0645\u0635\u0627\u0631\u0641 \u0648\u0634\u0631\u0643\u0627\u062a \u0627\u0644\u062a\u0623\u0645\u064a\u0646 \u0648\u0625\u064a\u0636\u0627\u062d \u062c\u0644 \u0627\u0644\u0645\u0639\u0627\u0645\u0644\u0627\u062a \u0627\u0644\u0645\u0635\u0631\u0641\u064a\u0629 \u0648\u062a\u062a\u0628\u0639\u0647\u0627 \u0627\u0644\u0645\u0635\u0627\u0631\u0641 \u0648\u0634\u0631\u0643\u0627\u062a \u0627\u0644\u062a\u0623\u0645\u064a\u0646.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22291\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u0645\u062e\u0631\u062c\u0627\u062a\u0627\u0644\u062a\u0639\u0644\u064a\u0645\u064a\u0629 (ILOs)\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22291\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2280\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u062a\u0639\u0631\u064a\u0641 \u0627\u0644\u0637\u0627\u0644\u0628 \u0628\u0627\u0644\u0645\u0641\u0627\u0647\u064a\u0645 \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u064a\u0629 \u0641\u064a \u0645\u062c\u0627\u0644 \u0627\u0644\u0628\u0646\u0648\u0643 \u0648\u0634\u0631\u0643\u0627\u062a \u0627\u0644\u062a\u0623\u0645\u064a\u0646\u060c \u062a\u0639\u0631\u064a\u0641 \u0627\u0644\u0637\u0627\u0644\u0628 \u0628\u0645\u0643\u0648\u0646\u0627\u062a \u0627\u0644\u0646\u0638\u0627\u0645 \u0627\u0644\u0645\u0635\u0631\u0641\u064a \u0641\u064a \u0644\u064a\u0628\u064a\u0627\u060c \u062a\u0639\u0631\u064a\u0641 \u0627\u0644\u0637\u0627\u0644\u0628 \u0628\u0627\u0644\u0645\u0641\u0627\u0647\u064a\u0645 \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u064a\u0629 \u0641\u064a \u0645\u062c\u0627\u0644 \u0627\u0644\u0628\u0646\u0648\u0643 \u0648\u0634\u0631\u0643\u0627\u062a \u0627\u0644\u062a\u0623\u0645\u064a\u0646\u060c\u00a0 \u0628\u064a\u0627\u0646 \u0627\u0644\u0643\u064a\u0641\u064a\u0629 \u0627\u0644\u062a\u064a \u062a\u062a\u0645 \u0628\u0647\u0627 \u0627\u0644\u0645\u0639\u0627\u0644\u062c\u0629 \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u064a\u0629 \u0644\u0644\u0639\u0645\u0644\u064a\u0627\u062a \u0627\u0644\u0635\u0631\u0641\u064a\u0629 \u0648\u0641\u0642\u0627\u064b \u0644\u0644\u0642\u0648\u0627\u0646\u064a\u0646 \u0648\u0627\u0644\u062a\u0634\u0631\u064a\u0639\u0627\u062a \u0627\u0644\u0644\u064a\u0628\u064a\u0629\u060c \u0627\u0644\u062a\u0639\u0631\u064a\u0641 \u0628\u0627\u0644\u0645\u0641\u0627\u0647\u064a\u0645 \u0648\u0627\u0644\u0623\u0633\u0633 \u0627\u0644\u0645\u062a\u0628\u0639\u0629 \u0645\u0646 \u0642\u0628\u0644 \u0634\u0631\u0643\u0627\u062a \u0627\u0644\u062a\u0623\u0645\u064a\u0646 \u0627\u0644\u0639\u0627\u0645\u0644\u0629 \u0648\u0641\u0642\u0627\u064b \u0644\u0644\u0642\u0627\u0646\u0648\u0646 \u0627\u0644\u0644\u064a\u0628\u064a\u060c \u0627\u0644\u062a\u0639\u0631\u0641 \u0639\u0644\u064a \u0627\u0644\u0645\u0639\u0627\u0644\u062c\u0627\u062a \u0627\u0644\u0645\u062d\u0627\u0633\u0628\u064a\u0629 \u0641\u064a \u0634\u0631\u0643\u0627\u062a \u0627\u0644\u062a\u0623\u0645\u064a\u0646 \u0648\u0641\u0642\u0627\u064b \u0644\u0644\u062a\u0634\u0631\u064a\u0639 \u0627\u0644\u0644\u064a\u0628\u064a.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22391\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0637\u0631\u064a\u0642\u0629\u0627\u0644\u062a\u062f\u0631\u064a\u0633 Teaching Strategy\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22391\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2280\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>1. \u0627\u0644\u0645\u062d\u0627\u0636\u0631\u0627\u062a \u0627\u0644\u062f\u0631\u0627\u0633\u064a\u0629 .<\/p>\n<p>2. \u00a0\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629<\/p>\n<p>3. \u0627\u0639\u062f\u0627\u062f \u0627\u0648\u0631\u0627\u0642 \u0628\u062d\u062b\u064a\u0629 \u0648\u0645\u0646\u0627\u0642\u0634\u062a\u0647\u0627<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22491\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u062a\u0642\u064a\u064a\u0645 Assessment\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22491\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2280\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u062a\u062a\u0645 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0639\u0645\u0644 \u0627\u0645\u062a\u062d\u0627\u0646 \u062a\u062d\u0631\u064a\u0631\u064a \u0646\u0635\u0641\u0649\u060c \u0648\u0634\u0641\u0648\u064a\u060c \u0648\u0648\u0627\u062c\u0628 \u062f\u0631\u0627\u0633\u064a\u060c \u0648\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 \u0648\u0627\u0645\u062a\u062d\u0627\u0646 \u0646\u0647\u0627\u0626\u0649. .<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-12 m-b30\">\r\n\t\t\t\t\t\t\t<h2 class=\"m-b10 m-t0\">\r\n\t\t\t\t\t\t\t\t\u0646\u0638\u0631\u064a\u0629 \u062a\u0646\u0638\u064a\u0645\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<p>\r\n\t\t\t\t\t\t\t\t110\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<div class=\"dez-accordion space\" id=\"accordionF48C2289\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22169\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0646\u0638\u0631\u0629 \u0639\u0627\u0645\u0629 \u0639\u0646 \u0627\u0644\u0645\u0642\u0631\u0631\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22169\" class=\"acod-body collapse show\" data-parent=\"#accordionF48C2289\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0645\u0646\u0627\u0642\u0634\u0629 \u0627\u0644\u0646\u0638\u0631\u064a\u0627\u062a \u0627\u0644\u062a\u0646\u0638\u064a\u0645\u064a\u0629 \u0648\u0639\u0644\u0627\u0642\u062a\u0647\u0627 \u0628\u0627\u0644\u0645\u0645\u0627\u0631\u0633\u0627\u062a \u0627\u0644\u0627\u062f\u0627\u0631\u064a\u0629 \u0648\u0643\u0630\u0644\u0643 \u0634\u0631\u062d \u0627\u0644\u0642\u0636\u0627\u064a\u0627 \u0627\u0644\u0645\u062a\u0639\u0644\u0642\u0629 \u0628\u0627\u0644\u0648\u0635\u0641 \u0627\u0644\u062a\u0646\u0638\u064a\u0645\u064a \u0648\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u0628\u062f\u0627\u0626\u0644 \u0648\u062a\u0642\u064a\u064a\u0645\u0647\u0627 \u0648\u062a\u0637\u0648\u064a\u0631 \u0627\u0644\u0642\u0631\u0627\u0631\u0627\u062a \u0623\u064a\u0636\u0627 \u064a\u0644\u0645 \u0627\u0644\u0637\u0627\u0644\u0628 \u0628\u0645\u0631\u0627\u062d\u0644 \u062a\u0637\u0648\u0631 \u0627\u0644\u0641\u0643\u0631 \u0627\u0644\u0627\u062f\u0627\u0631\u064a \u0648\u0627\u0644\u0643\u062a\u0627\u0628\u0627\u062a \u0627\u0644\u062a\u064a \u0627\u0633\u0647\u0645\u062a \u0641\u064a\u0647\u060c \u0623\u0646 \u064a\u0643\u0648\u0646 \u0642\u0627\u062f\u0631\u0627 \u0639\u0644\u064a \u062a\u0639\u0631\u064a\u0641 \u0646\u0638\u0631\u064a\u0629 \u0627\u0644\u0627\u062f\u0627\u0631\u0629 \u0648\u0623\u064a\u0636\u0627 \u062a\u0641\u0633\u064a\u0631 \u0627\u0644\u0646\u062a\u0627\u0626\u062c \u0627\u0644\u0645\u062a\u0631\u062a\u0628\u0629 \u0639\u0644\u064a \u0631\u0628\u0637 \u0627\u0644\u062a\u0637\u0648\u0631 \u0627\u0644\u0641\u0643\u0631\u064a \u0627\u0644\u0627\u062f\u0627\u0631\u064a \u0628\u0645\u0628\u0627\u062f\u0626 \u0648\u0641\u0631\u0648\u0636 \u0646\u0638\u0631\u064a\u0629 \u0627\u0644\u062a\u0646\u0638\u064a\u0645 .<\/p>\n<p>&nbsp;<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22269\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u0645\u062e\u0631\u062c\u0627\u062a \u0627\u0644\u062a\u0639\u0644\u064a\u0645\u064a\u0629\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22269\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2289\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0627\u0644\u0642\u062f\u0631\u0629 \u0639\u0644\u064a \u062a\u062d\u0644\u064a\u0644 \u0627\u0644\u0628\u064a\u0626\u0629 \u0627\u0644\u0645\u0646\u0638\u0645\u0629 \u0648\u0642\u064a\u0627\u0633 \u0641\u0627\u0639\u0644\u064a\u0629 \u0627\u0644\u0645\u0646\u0638\u0645\u0629 \u0648\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0628\u0646\u0627\u0621 \u0627\u0644\u062a\u0646\u0638\u064a\u0645\u064a \u0627\u0644\u0630\u064a \u064a\u0645\u0643\u0646\u0647 \u0645\u0646 \u062a\u0642\u064a\u064a\u0645 \u062f\u0648\u0631 \u0648\u0645\u062c\u0647\u0648\u062f\u0627\u062a \u0627\u0644\u062a\u0646\u0638\u064a\u0645\u0627\u062a \u0641\u064a \u0627\u0644\u0627\u0631\u062a\u0642\u0627\u0621 \u0628\u0623\u0633\u0633 \u0648\u0645\u0628\u0627\u062f\u064a \u0627\u0644\u0641\u0643\u0631 \u0627\u0644\u0627\u062f\u0627\u0631\u064a , \u0648\u0627\u064a\u0636\u0627 \u0627\u0644\u0627\u0633\u062a\u0641\u0627\u062f\u0629 \u0645\u0646 \u0627\u0644\u0645\u0628\u0627\u062f\u064a \u0648\u0627\u0644\u0641\u0631\u0648\u0636 \u0627\u0644\u0645\u062a\u0639\u0644\u0642\u0629 \u0628\u0627\u0644\u0646\u0638\u0631\u064a\u0629 \u0627\u0644\u0627\u062f\u0627\u0631\u064a\u0629 \u0641\u064a \u0627\u0644\u0642\u062f\u0631\u0629 \u0639\u0644\u064a \u0627\u0644\u062a\u063a\u064a\u064a\u0631 \u0648\u0627\u0639\u0627\u062f\u0629 \u0627\u0644\u0647\u064a\u0643\u0644\u064a\u0629 .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22369\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u062f\u0631\u064a\u0633\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22369\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2289\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>&nbsp;<\/p>\n<p>1.\u0627\u0644\u0645\u062d\u0627\u0636\u0631\u0627\u062a \u0627\u0644\u062f\u0631\u0627\u0633\u064a\u0629 .<\/p>\n<p>2.\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 .<\/p>\n<p>3.\u0627\u0639\u062f\u0627\u062f \u0627\u0648\u0631\u0627\u0642 \u0628\u062d\u062b\u064a\u0629 \u0648\u0645\u0646\u0627\u0642\u0634\u062a\u0647\u0627 .<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"panel\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"acod-head\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"acod-title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t<a data-toggle=\"collapse\" href=\"#\" data-target=\"#collapseF48C22469\" aria-expanded=\"false\" class=\"collapsed\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-question-circle\"><\/i> \u0627\u0644\u062a\u0642\u064a\u064a\u0645\t\t\t\t\t\t\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t<\/h6>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div id=\"collapseF48C22469\" class=\"acod-body collapse \" data-parent=\"#accordionF48C2289\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"acod-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u062a\u062a\u0645 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0639\u0645\u0644 \u0627\u0645\u062a\u062d\u0627\u0646 \u062a\u062d\u0631\u064a\u0631\u064a \u0646\u0635\u0641\u0649\u060c \u0648\u0634\u0641\u0648\u064a\u060c \u0648\u0648\u0627\u062c\u0628 \u062f\u0631\u0627\u0633\u064a\u060c \u0648\u062d\u0644\u0642\u0627\u062a \u0646\u0642\u0627\u0634 \u062f\u0627\u062e\u0644 \u0627\u0644\u0642\u0627\u0639\u0629 \u0648\u0627\u0645\u062a\u062d\u0627\u0646 \u0646\u0647\u0627\u0626\u0649. .<\/p>\n<p>&nbsp;<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\t\t\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n\t<!-- Faq END -->\r\n[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"redux-templates_full_width","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[59],"tags":[],"class_list":["post-2604","post","type-post","status-publish","format-standard","hentry","category-59"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/fezzanu.edu.ly\/fecon\/wp-json\/wp\/v2\/posts\/2604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fezzanu.edu.ly\/fecon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fezzanu.edu.ly\/fecon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fezzanu.edu.ly\/fecon\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fezzanu.edu.ly\/fecon\/wp-json\/wp\/v2\/comments?post=2604"}],"version-history":[{"count":1,"href":"https:\/\/fezzanu.edu.ly\/fecon\/wp-json\/wp\/v2\/posts\/2604\/revisions"}],"predecessor-version":[{"id":2605,"href":"https:\/\/fezzanu.edu.ly\/fecon\/wp-json\/wp\/v2\/posts\/2604\/revisions\/2605"}],"wp:attachment":[{"href":"https:\/\/fezzanu.edu.ly\/fecon\/wp-json\/wp\/v2\/media?parent=2604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fezzanu.edu.ly\/fecon\/wp-json\/wp\/v2\/categories?post=2604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fezzanu.edu.ly\/fecon\/wp-json\/wp\/v2\/tags?post=2604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}